{"id":32345,"date":"2014-04-21T04:15:10","date_gmt":"2014-04-21T02:15:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/pasquetta-grigia-su-due-fronti-meteo-e-portafogli\/"},"modified":"2023-01-17T12:52:21","modified_gmt":"2023-01-17T11:52:21","slug":"13847-pasquetta-grigia-su-due-fronti-meteo-e-portafogli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13847-pasquetta-grigia-su-due-fronti-meteo-e-portafogli\/","title":{"rendered":"Pasquetta &#8216;grigia&#8217; su due fronti: meteo e portafogli"},"content":{"rendered":"<p>CATANZARO &#8211; Pasquetta \u2018grigia\u2019 economicamente e sotto il profilo meteo.<\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 1;\">Il tempo non sar\u00e0 dei migliori e neanche il portafogli \u00e8 cos\u00ec pieno da consentire agli italiani, e in particolar modo ai calabresi, di spendere in vacanze e dunque di partire una mini vacanza. L&#8217;andamento generale dello stivale dipende in particolare da 4 variabili indipendenti: meteo, traffico, salute e soldi. A sostenerlo \u00e8 Trademark Italia, secondo la quale non c&#8217;\u00e8 traccia di &#8220;tutto esaurito&#8221; negli alberghi italiani. Quasi un italiano su 4 (il 23%) voler\u00e0 verso una citt\u00e0 europea e la meta preferita pare sia la Spagna (Barcellona, Valencia e Madrid), davanti a Londra e Parigi; le richieste per Istanbul superano quelle per Berlino e Amsterdam. In flessione le prenotazioni pasquali per Vienna, Budapest e Praga. La situazione instabile in Egitto penalizza il Mar Rosso, mentre aumentano le richieste per le isole Canarie. Una Pasqua grigia dunque, quella degli italiani, con qualche segnale di ottimismo solo per i gestori di ristoranti tradizionali. Infatti l&#8217;89% degli italiani (rispetto all&#8217;85% dello scorso anno) si limiter\u00e0 ad uscire di casa per il pranzo di Pasqua o per la classica gita &#8220;fuori porta&#8221; di Pasquetta. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 1;\"><strong>Ma la spesa?<\/strong> <\/span><\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 1;\">Secondo una stima sulle vacanze pasquali, la spesa media pro-capite per tre giorni fuori casa, per ogni italiano, \u00e8 di 290 euro. Si stima che la spesa diretta fuori casa dei circa sette milioni di turisti di Pasqua ammonti a poco pi\u00f9 di due miliardi di euro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 1;\"><strong>Il Traffico<\/strong><\/span><\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 1;\">Attenzione anche al traffico perch\u00e9 se avete intenzione di mettervi in macchina e spostarsi sappiate che, oltre all\u2019<strong>aumento del costo dei carburanti<\/strong>, c\u2019\u00e8 anche il rischio di incappare in lunghe code. Sulle autostrade italiane il traffico di automezzi \u00e8 stimato in crescita del +4,3%. Grande aumento del traffico ferroviario (+15%) grazie all&#8217;Alta Velocit\u00e0 (circa 1,7-1,8 milioni di italiani utilizzeranno le Frecce per spostarsi). Per chi \u00e8 partito, i rientri sono concentrati per la giornata di oggi, tra le ore 16.00 e le 22.00 e per l&#8217;intera giornata di domani, marted\u00ec 22 aprile. Per agevolare gli spostamenti, i mezzi pesanti non potranno circolare oggi dalle 08.00 alle 22.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Pasquetta \u2018grigia\u2019 economicamente e sotto il profilo meteo.<\/p>\n","protected":false},"author":22,"featured_media":32346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32345"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32346"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}