{"id":32363,"date":"2014-04-22T04:36:00","date_gmt":"2014-04-22T02:36:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/diciottenne-ferito-a-colpi-d-arma-da-fuoco-a-monasterace\/"},"modified":"2023-01-17T12:52:22","modified_gmt":"2023-01-17T11:52:22","slug":"13856-diciottenne-ferito-a-colpi-d-arma-da-fuoco-a-monasterace","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13856-diciottenne-ferito-a-colpi-d-arma-da-fuoco-a-monasterace\/","title":{"rendered":"Diciottenne ferito a colpi d&#8217;arma da fuoco a Monasterace"},"content":{"rendered":"<p>MONASTERACE (RC) &#8211; Sar\u00e0 risentito in queste ore il diciottenne ferito da un colpo d&#8217;arma da fuoco a Monasterace.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il ragazzo \u00e8 stato colpito alla spalla da un colpo di pistola mentre si trovava in compagnia di un amico nelle campagne di Monasterace. Proprio il suo amico, lo avrebbe accompagnato al pronto soccorso dell\u2019ospedale di Soverato per essere sottoposto alle cure del caso. Il ragazzo \u00e8 stato ricoverato in prognosi riservata ed ha raccontato di essere stato colpito ma di non sapere chi sia stato. Sull&#8217;episodio hanno gi\u00e0 avviato indagini i Carabinieri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONASTERACE (RC) &#8211; Sar\u00e0 risentito in queste ore il diciottenne ferito da un colpo d&#8217;arma da fuoco a Monasterace.<\/p>\n","protected":false},"author":19,"featured_media":32364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32363"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32364"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}