{"id":32715,"date":"2014-05-03T13:12:22","date_gmt":"2014-05-03T11:12:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/l-ora-della-calabria\/"},"modified":"2023-01-17T12:52:44","modified_gmt":"2023-01-17T11:52:44","slug":"14036-l-ora-della-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14036-l-ora-della-calabria\/","title":{"rendered":"Chiusura dell&#8217;Ora della Calabria, Nicol\u00f2: &#8216;Una sconfitta per tutti&#8217;"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Mentre Scopelliti nega la solidariet\u00e0 ai 66 giornalisti licenziati dopo la chiusura dell&#8217;Ora della Calabria, il vicepresidente del Consiglio regionale Nicol\u00f2 usa parole dure per descrivere la vicenda delle ingerenze del &#8216;cinghiale&#8217; nell&#8217;editoria calabrese.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&#8220;La chiusura di un giornale rappresenta, in qualsiasi circostanza, una sconfitta &#8211; ha sentenziato Alessandro Nicol\u00f2 riferendosi alla situazione del quotidiano calabrese edito dalla famiglia Citrigno &#8211; una perdita che ci lascia perplessi non solo riguardo la soppressione di un organo di stampa che contribuisce ad assicurare il diritto all&#8217;informazione, ma anche rispetto al destino dei giornalisti e dei dipendenti, destinatari di una misura di licenziamento collettivo. Esprimo quindi la mia sentita solidariet\u00e0 a tutti i giornalisti ed ai dipendenti de &#8216;l&#8217;Ora della Calabria&#8217; che, comprensibilmente, stanno tentando da giorni di fare sentire la loro voce. Il chiaro messaggio da parte dei lavoratori giunge come un campanello d&#8217;allarme rispetto al rischio di dispersione di competenze ed esperienze importanti di giovani calabresi che si sono spesi, sempre con impegno, per garantire una continuit\u00e0 nel fondamentale servizio di informare quotidianamente i cittadini e di contribuire, con questo, alla costruzione di una coscienza critica sui fatti. <strong>L&#8217;auspicio, dunque \u00e8 quello di raggiungere una soluzione di buon senso che, superate le criticit\u00e0, possa contenere i rischi di una nuova ondata di disoccupazione depauperando specifiche professionalit\u00e0 e che non venga altres\u00ec disperso, nelle pieghe della vertenza, il principio guida della libert\u00e0 di stampa e di espressione del pensiero.<\/strong> Mi appello alla sensibilit\u00e0 delle parti coinvolte affinch\u00e9 si possa giungere ad una rapida soluzione della vertenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Mentre Scopelliti nega la solidariet\u00e0 ai 66 giornalisti licenziati dopo la chiusura dell&#8217;Ora della Calabria, il vicepresidente del Consiglio regionale Nicol\u00f2 usa parole dure per descrivere la vicenda delle ingerenze del &#8216;cinghiale&#8217; nell&#8217;editoria calabrese.<\/p>\n","protected":false},"author":22,"featured_media":32716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32715"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32716"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}