{"id":32767,"date":"2014-05-05T10:44:03","date_gmt":"2014-05-05T08:44:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/10-anni-dopo-mr-and-mrs-smith-il-ritorno\/"},"modified":"2023-01-17T12:52:47","modified_gmt":"2023-01-17T11:52:47","slug":"14062-10-anni-dopo-mr-and-mrs-smith-il-ritorno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14062-10-anni-dopo-mr-and-mrs-smith-il-ritorno\/","title":{"rendered":"10 anni dopo Mr and Mrs Smith, il ritorno.."},"content":{"rendered":"<p>Ormai inseparabili nella vita e adesso di nuovo anche sul set.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Angelina Jolie e Brad Pitt tornano a fare un film insieme dopo 10 anni da quel galeotto Mr and Mrs Smith che li fece innamorare. Lo rivela in anteprima il sito specializzato Deadline.com, che parla di una sceneggiatura curata dalla stessa Jolie e che racconta di un dramma sulle relazioni sentimentali. Secondo l&#8217;Hollywood Reporter, l&#8217;attrice avrebbe scritto, gi\u00e0 vari anni fa, una sceneggiatura su una coppia che tenta di salvare il matrimonio in crisi concedendosi una ultima vacanza insieme. Del progetto non si sa altro, ma se si trattasse davvero di questa sceneggiatura Angelina potrebbe aver preso spunto dalle vicende sentimentali del compagno Brad Pitt quando si separ\u00f2 dall&#8217;allora moglie Jennifer Aniston. I due infatti, in crisi proprio proprio a causa dell&#8217;incontro di Pitt con la Jolie, sul set di Mr e Mrs Smith, decisero di andare in vacanza ai Caraibi per cercare, infruttuosamente, di ricucire lo strappo. Le fotografie della coppia mano nella mano in una spiaggia bianca di Aguilla, era il 2005, furono infatti le ultime catturate dai paparazzi prima della definitiva rottura. Per la Jolie sarebbe il terzo esperimento dietro la cinepresa (anche se in questo caso sarebbe anche coprotagonista). Dopo aver diretto nel 2011 In the Land of Blood and Honey, proprio in questi giorni la Jolie si sta occupando della post-produzione del suo film da regista, Unbroken, che racconta la vita di Louis Zamperini, il corridore olimpico che fu fatto prigioniero dai giapponesi durante la Seconda Guerra Mondiale. Anche Brad Pitt, che ha prodotto il film vincitore dell&#8217;Oscar 12 anni schiavo, sar\u00e0 a dicembre sugli schermi con il film sulla Seconda Guerra Mondiale, Fury, in cui interpreter\u00e0 in un sergente a capo di una missione suicida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ormai inseparabili nella vita e adesso di nuovo anche sul set.<\/p>\n","protected":false},"author":20,"featured_media":32768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34],"tags":[],"class_list":["post-32767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32767"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32768"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}