{"id":3279,"date":"2012-09-07T07:09:06","date_gmt":"2012-09-07T05:09:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3279"},"modified":"2023-01-17T13:35:46","modified_gmt":"2023-01-17T12:35:46","slug":"319-cuore-i-40enni-non-imparano-dalle-cattive-esperienze","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/319-cuore-i-40enni-non-imparano-dalle-cattive-esperienze\/","title":{"rendered":"Cuore, i 40enni non imparano dalle (cattive) esperienze"},"content":{"rendered":"<p>MILANO &#8211; Chi si ritrova con le coronarie mal messe prime dei 40 anni e deve ricorrere al palloncino e poi allo stent, ha buone probabilit\u00e0 che questi interventi lo preservino da ulteriori problemi nel medio-lungo periodo. A meno che il cuore sia gi\u00e0 stato seriamente danneggiato<\/p>\n<p>  <!--more-->  <\/p>\n<p>o che il paziente perseveri con uno stile dei vita a rischio, prima di tutto con il fumo. Questo il messaggio di una ricerca effettuata in pi\u00f9 centri cardiologici torinesi e pubblicata sull\u2019American Journal of Cardiology.<\/p>\n<p>GIOVANI SOLO PER L&#8217;ET\u00c0 &#8211; A illustrare i risultati \u00e8 Emanuele Meliga, cardiologo interventista dell\u2019Ospedale Mauriziano di Torino che ha coordinato lo studio. \u00abCi siamo chiesti quale fosse il destino dei pazienti che devono subire precocemente un\u2019angioplastica con impianto di stent. Abbiamo individuato oltre 200 casi, 9 su 10 maschi, trattati nel corso di un quinquennio. L\u2019et\u00e0 media era davvero bassa, 36 anni circa, e la maggior parte dei pazienti sono giunti alla nostra attenzione a seguito di infarto miocardico o sindrome coronarica acuta\u00bb. Effettivamente si trattava di un gruppo di persone con predisposizione a malattie coronariche sia in termini di fattori di rischio cardiovascolare (ipertensione, ipercolesterolemia, obesit\u00e0, diabete), sia per la abitudine al fumo, riferita dai tre quarti dei pazienti. L\u2019esperto torinese precisa: \u00abI dati clinici indicano chiaramente che, specialmente in questo tipo di pazienti, il fumo ha un peso determinante nel danneggiare le coronarie. Inoltre, abbiamo notato come in genere fossero presenti al momento del ricovero pi\u00f9 fattori di rischio cardiovascolare misconosciuti: solo il 5% di questi infatti aveva in passato fatto accertamenti o assunto farmaci per controllare la pressione, l\u2019ipercolesterolemia, il diabete, fidandosi troppo della giovane et\u00e0 e dell\u2019ingannevole convinzione di essere in salute. Il tipo di lesioni presenti sulle coronarie di questo gruppo era qualitativamente simile a quelle che si trovano nei pazienti pi\u00f9 anziani, come a dire che il mix di fumo e predisposizione individuale ha accelerato il processo di invecchiamento\u00bb.<\/p>\n<p>DARSI UNA REGOLATA &#8211; L\u2019angioplastica ha avuto successo e rare complicazioni nell\u2019immediato, ma la questione interessante era capire come andassero le cose a distanza di tempo. \u00abDopo un periodo di osservazione medio di circa due anni, quasi il 90% dei nostri pazienti non ha avuto eventi cerebrali o cardiovascolari maggiori, come morte, ictus, infarto e necessit\u00e0 di un re-intervento sulle coronarie &#8211; prosegue il cardiologo -. Peraltro i problemi si sono concentrati in quel ristretto sottogruppo di pazienti che avevano una funzione cardiaca compromessa dai primi episodi di malattia o che avevano continuato a fumare\u00bb. La morale della storia non \u00e8 difficile da capire, forse pi\u00f9 difficile da applicare: per evitare di trovarsi a 40 anni con le coronarie di un uomo di 20 o 30 anni pi\u00f9 vecchio, bisogna ricercare uno stile di vita salutare (la ricetta comprende la rinuncia al fumo, all\u2019eccesso di alcol, l\u2019alimentazione moderata per quantit\u00e0 e selezionata per qualit\u00e0, l\u2019attivit\u00e0 fisica) e una visita dal medico anche se ci si sente in gran forma, magari dal cardiologo se in famiglia c\u2019\u00e8 qualcuno che ne ha avuto bisogno in passato. Soprattutto non vale la pena di sfidare la sorte se \u00e8 gi\u00e0 stata benevola una prima volta, permettendo di risolvere con l\u2019angioplastica una minaccia per la vita almeno all\u2019inizio ignorata. Ecco perch\u00e9 non ha senso perseverare con il fumo. Qualche dato scientifico, a conforto di chi non \u00e8 abbastanza motivato a buttare via la sigaretta: dopo un anno dalla cessazione il rischio di infarto si riduce del 50%, dopo 5 anni il rischio di malattia coronarica grave e dopo 5-15 anni il rischio di ictus ritornano gli stessi dei non fumatori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILANO &#8211; Chi si ritrova con le coronarie mal messe prime dei 40 anni e deve ricorrere al palloncino e poi allo stent, ha buone probabilit\u00e0 che questi interventi lo preservino da ulteriori problemi nel medio-lungo periodo. A meno che il cuore sia gi\u00e0 stato seriamente danneggiato<\/p>\n","protected":false},"author":22,"featured_media":482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,5,52],"tags":[],"class_list":["post-3279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-old","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3279"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/482"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}