{"id":32828,"date":"2014-05-06T16:31:54","date_gmt":"2014-05-06T14:31:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/stalker-arrestato-dalla-polizia-a-cosenza\/"},"modified":"2023-01-17T12:52:52","modified_gmt":"2023-01-17T11:52:52","slug":"14093-stalker-arrestato-dalla-polizia-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14093-stalker-arrestato-dalla-polizia-a-cosenza\/","title":{"rendered":"Stalker arrestato dalla Polizia a Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Un uomo di 68 anni, G.Z., di Cosenza, \u00e8 stato arrestato e posto agli arresti domiciliari dalla Questura di Cosenza.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il provvedimento \u00e8 stato emesso dal GIP Cristofano su richiesta del sostituto procuratore Tridico. Secondo le indagini della squadra mobile, l\u2019uomo avrebbe minacciato e perseguitato alcuni vicini per circa quattro anni. La diatriba, sorta per banali incomprensioni condominiali, \u00e8 sfociata poi in atteggiamenti ossessivi compulsivi da parte dell\u2019uomo, gi\u00e0 condannato nel Dicembre scorso per lesioni personali, minacce ed ingiurie nei confronti delle vittime odierne<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un uomo di 68 anni, G.Z., di Cosenza, \u00e8 stato arrestato e posto agli arresti domiciliari dalla Questura di Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":32829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-32828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32828"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32829"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}