{"id":32838,"date":"2014-05-07T05:51:48","date_gmt":"2014-05-07T03:51:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cagnolino-impiccato-a-montalto-un-gesto-vile-e-crudele\/"},"modified":"2023-01-17T12:52:52","modified_gmt":"2023-01-17T11:52:52","slug":"14098-cagnolino-impiccato-a-montalto-un-gesto-vile-e-crudele","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14098-cagnolino-impiccato-a-montalto-un-gesto-vile-e-crudele\/","title":{"rendered":"Cagnolino impiccato, troppi i casi di crudelt\u00e0 a Montalto"},"content":{"rendered":"<p>MONTALTO UFFUGO (CS) &#8211; Un cucciolo vittima di una cieca violenza, da parte di chi probabilmente non ha sentimenti di piet\u00e0.<\/p>\n<p>  <!--more-->  <\/p>\n<p>E&#8217; stato trovato da cittadini del luogo disteso a terra, con ancora al collo il laccio utilizzato per il vile gesto. Impiccato e ucciso senza alcuna piet\u00e0. Vittima della violenza cieca e spietata di &#8216;qualcuno&#8217;. Un fatto che ha suscitato orrore e sdegno tra i cittadini. Il cagnolino, un bastardino, \u00e8 stato prima impiccato sotto la pedana che consente l\u2019accesso nella chiesa della Madonna della Serra di Montalto Uffugo, e poi lasciato cadere privo di vita nell\u2019erba. I cittadini chiedono che il responsabile venga identificato e che paghi per questo gesto di crudelt\u00e0. A Montalto infatti, pare ci sia &#8216;qualcuno&#8217; che sembri avercela proprio con i cani. Un anno fa un\u2019altro gesto simile: avvelenato in piazza Enrico Bianco un cagnolino ed un altro rinchiuso, lo scorso mese di marzo, segregato in un canale. Un setter inglese infatti era stato bloccato all&#8217;uscita di un canale dove trovava rifugio con delle pietre. Per fortuna \u00e8 stato liberato. A Montalto dunque, qualche delinquente, pare si diverta a torturare i cani e i residenti si appellano alle forze dell&#8217;ordine affinch\u00e8 questa persona venga fermata al pi\u00f9 presto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO (CS) &#8211; Un cucciolo vittima di una cieca violenza, da parte di chi probabilmente non ha sentimenti di piet\u00e0.<\/p>\n","protected":false},"author":19,"featured_media":32839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-32838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32838"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32839"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}