{"id":32895,"date":"2014-05-08T12:28:10","date_gmt":"2014-05-08T10:28:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/terapie-farmacologiche-prescrizioni-allegre-all-annunziata\/"},"modified":"2023-01-17T12:52:57","modified_gmt":"2023-01-17T11:52:57","slug":"14128-terapie-farmacologiche-prescrizioni-allegre-all-annunziata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14128-terapie-farmacologiche-prescrizioni-allegre-all-annunziata\/","title":{"rendered":"L&#8217;Asp dalle consulenze d&#8217;oro taglia farmaci e analisi di laboratorio"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA &#8211; La Regione deve risparmiare e l&#8217;Asp di Cosenza chiede di limitare terapie ed esami diagnostici.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Eppure quando si regalavano le consulenze agli avvocati amici, amici di amici e figli di amici nessuno pens\u00f2 di porre un freno alle spese faraoniche destinate ai legali. A segnalare l&#8217;ultima delle trovate per il Piano di Rientro dal debito sanitario a cui \u00e8 sottoposta la Regioner, cui delega alla sanit\u00e0, ricordiamo, \u00e8 affidata al governatore dimissionario Giuseppe Scopelliti, \u00e8 lo SMI, il sindacato medici italiani. &#8220;Nei giorni scorsi &#8211; spiega in una nota il sindacato &#8211; l\u2019ennesima circolare del direttore generale dell\u2019ASP di Cosenza riproponeva l\u2019annoso tema dell\u2019<strong>accortezza che i medici dovrebbero avere nel prescrivere terapie, esami diagnostici e strumentali con parsimonia<\/strong>. Siamo pienamente d\u2019accordo nel ribadire che <strong>la eliminazione di sprechi in sanit\u00e0 va sicuramente perseguita ma certamente non con puri tagli alle cure ma con una razionalizzazione delle spese. D<\/strong>enunciamo la discriminazione effettuata nei confronti dei medici di famiglia da parte degli organi di controllo della spesa farmaceutica delle ASP. Dal 2002 esiste una norma di legge che obbliga tutti i medici del Servizio Sanitario Nazionale a prescrivere sul ricettario rosso le cure e le indagini strumentali e di laboratorio ritenute opportune al caso clinico. Un&#8217;imposizione che riduce il medico di famiglia ad assumere il ruolo mortificante di trascrittore di ricette in bianco senza diagnosi, firma o timbro di un altro collega richiedente. Ed alla beffa si aggiunge anche il danno, questa volta economico, risultante dal fatto che solo le ricette dei medici di famiglia arrivano sul tavolo delle Commissioni Aziendali quindi eventuali errori od omissioni vengono contestati solo a questa categoria. L\u2019Ordine dei Medici ha deciso di intraprendere iniziative eclatanti per costringere tutti i medici del SSN al rispetto delle regole&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La Regione deve risparmiare e l&#8217;Asp di Cosenza chiede di limitare terapie ed esami diagnostici.<\/p>\n","protected":false},"author":18,"featured_media":32896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-32895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32895"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32896"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}