{"id":32907,"date":"2014-05-09T06:41:59","date_gmt":"2014-05-09T04:41:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/evasione-fiscale-per-5mln-di-euro-imprenditore-denunciato\/"},"modified":"2023-01-17T12:52:57","modified_gmt":"2023-01-17T11:52:57","slug":"14134-evasione-fiscale-per-5mln-di-euro-imprenditore-denunciato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14134-evasione-fiscale-per-5mln-di-euro-imprenditore-denunciato\/","title":{"rendered":"Evasione fiscale per 5mln di euro, imprenditore denunciato"},"content":{"rendered":"<p>GIOIOSA JONICA (RC) &#8211; Avrebbe sottratto al fisco ricavi per quattro milioni di euro evadendo l&#8217;Iva per circa un milione.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un commerciante di Marina di Gioiosa Jonica \u00e8 stato denunciato dalla Guardia di finanza al termine di una verifica fiscale dei finanzieri che hanno accertato come &nbsp;l&#8217;esercente, attivo nella vendita al dettaglio di abbigliamento di alta moda, con due punti vendita, pur avendo ricavi superiori al milione, dichiarava un utile pari a 468 euro per il 2011. La verifica avviata dai finanzieri nei confronti del commerciante che gestiva due punti vendita a Marina di Gioiosa Jonica e Roccella Jonica, \u00e8 stata mirata alla ricostruzione del reale giro di affari realizzato negli ultimi anni, un lavoro che ha portato alla luce l&#8217;entit\u00e0 dei ricavi e, di conseguenza, l&#8217;evasione di Iva perpetrata. Gli accertamenti compiuti dai finanzieri, per\u00f2, si sono rivelati particolarmente difficoltosi a causa dell&#8217;omessa istituzione di scritture contabili da parte dell&#8217;impresa negli ultimi anni oggetto di ispezione. In particolare, si \u00e8 riusciti a venire a capo dell&#8217;evasione grazie al minuzioso e capillare rilevamento delle giacenze di magazzino esistenti nei locali che ha permesso di riscontrare una rilevante anomalia rispetto al valore di rimanenze contabili dichiarate al fisco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIOSA JONICA (RC) &#8211; Avrebbe sottratto al fisco ricavi per quattro milioni di euro evadendo l&#8217;Iva per circa un milione.<\/p>\n","protected":false},"author":19,"featured_media":32908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32907"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32908"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}