{"id":32935,"date":"2014-05-09T11:41:59","date_gmt":"2014-05-09T09:41:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/incidente-mortale-a-cosenza-a-perdere-la-vita-e-un-trentenne\/"},"modified":"2023-01-17T12:53:00","modified_gmt":"2023-01-17T11:53:00","slug":"14149-incidente-mortale-a-cosenza-a-perdere-la-vita-e-un-trentenne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14149-incidente-mortale-a-cosenza-a-perdere-la-vita-e-un-trentenne\/","title":{"rendered":"Incidente mortale, trentenne perde la vita schiantandosi su piazza Loreto"},"content":{"rendered":"<p>COSENZA &#8211; Voleva evitare di scontrarsi con quell&#8217;auto sbucata all&#8217;improvviso in controsenso da una traversa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Francesco Corallo, trentenne noto in citt\u00e0 per aver lavorato in diversi locali notturni, \u00e8 deceduto stanotte a seguito di un incidente stradale avvenuto intorno alle 3 del mattino. La dinamica dei fatti \u00e8 ancora in fase di accertamento. Secondo i primi rilievi dopo le scuole elementari dell&#8217;ex via Roma (via Misasi) il giovane avrebbe sterzato per evitare la collisione con una vettura proveniente dalla traversa che porta su viale della Repubblica. La vettura di Corallo avrebbe cos\u00ec colpito un muro per poi terminare la sua corsa schiantandosi contro un albero in piazza Loreto. La vittima \u00e8 morta sul colpo. I sanitari accorsi sul posto non hanno potuto far altro se non constatare l&#8217;avvenuto decesso. Le forze dell&#8217;ordine indagano per individuare chi e cosa avrebbe causato lo sbandamento della vettura guidata da Francesco Corallo sul cui corpo \u00e8 gi\u00e0 stata disposta l&#8217;autopsia.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Voleva evitare di scontrarsi con quell&#8217;auto sbucata all&#8217;improvviso in controsenso da una traversa.<\/p>\n","protected":false},"author":18,"featured_media":32936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-32935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32935"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32936"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}