{"id":32975,"date":"2014-05-12T05:49:42","date_gmt":"2014-05-12T03:49:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ndrangheta-sigilli-ai-beni-di-presunti-affiliati-al-clan-tegano\/"},"modified":"2023-01-17T12:53:02","modified_gmt":"2023-01-17T11:53:02","slug":"14169-ndrangheta-sigilli-ai-beni-di-presunti-affiliati-al-clan-tegano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14169-ndrangheta-sigilli-ai-beni-di-presunti-affiliati-al-clan-tegano\/","title":{"rendered":"&#8216;Ndrangheta, sigilli ai beni di presunti affiliati al clan Tegano"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Sigilli a titoli e propriet\u00e0 riconducibili a presunti affiliati alla cosca Tegano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Stamattina la Guardia di Finanza ha sequestrato beni mobili e immobili per 10 milioni di euro, a presunti affiliati alla cosca Tegano di Reggio Calabria. I destinatari dei provvedimenti, emessi dalla sezione misure prevenzione del Tribunale al termine di indagini coordinate dalla Dda a seguito dell&#8217;operazione &#8220;Coffee Break&#8221; sono gli imprenditori Giuseppe Lavilla e i figli Antonio e Maurizio. Antonio Lavilla \u00e8 sposato con Saveria Tegano figlia del boss Giovanni. I finanzieri di Reggio Calabria, anche sulla base delle indicazioni di numerosi collaboratori di giustizia che hanno fornito utili dichiarazioni indicando i Lavilla come al soldo della cosca Tegano, hanno ricostruito il patrimonio personale e imprenditoriale degli imprenditori reggini. Attraverso un&#8217;accurata rielaborazione dei dati fiscali e patrimoniali acquisiti, \u00e8 emersa, in particolare, la notevole sperequazione tra redditi dichiarati dagli imprenditori e incremento patrimoniale accertato. Conseguentemente si \u00e8 proceduto ad una nuova e definitiva analisi contabile che ha consentito di evidenziare un eccezionale arricchimento patrimoniale dei Lavilla realizzato nel corso degli ultimi anni. Il provvedimento di sequestro ha riguardato beni mobili, immobili ed attivit\u00e0 commerciali soprattutto nel settore dell&#8217;edilizia e del noleggio di distributori automatici di alimenti. Tra le societ\u00e0 cadute nella rete spicca la Calabra Vending srl, leader nella distribuzione di macchine automatiche per la vendita di caff\u00e8 ed alimenti. La societ\u00e0 ultimamente stava commercializzando una nuova marca di caff\u00e8, &#8220;Caff\u00e8 Lavilla&#8221;. Tra gli immobili oggetto del sequestro vi \u00e8 un intero palazzo, in corso di realizzazione. I sigilli, inoltre, sono stati apposti a quote societarie e diverse unit\u00e0 immobiliari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Sigilli a titoli e propriet\u00e0 riconducibili a presunti affiliati alla cosca Tegano.<\/p>\n","protected":false},"author":22,"featured_media":32976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32975"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32976"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}