{"id":33056,"date":"2014-05-14T06:40:54","date_gmt":"2014-05-14T04:40:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/imprenditore-fallisce-invece-del-suicidio-sceglie-di-abitare-in-piazza-duomo\/"},"modified":"2023-01-17T12:53:34","modified_gmt":"2023-01-17T11:53:34","slug":"14212-imprenditore-fallisce-invece-del-suicidio-sceglie-di-abitare-in-piazza-duomo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14212-imprenditore-fallisce-invece-del-suicidio-sceglie-di-abitare-in-piazza-duomo\/","title":{"rendered":"Imprenditore fallisce, invece del suicidio sceglie di &#8216;abitare&#8217; in piazza Duomo"},"content":{"rendered":"<p>MILANO \u2013 Il suicidio negli ultimi tempi pare essere diventato la via pi\u00f9 risolutiva per gli imprenditori.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Assaliti da debiti e da un sentirsi inetto. Malgrado uno stato psicologico fragile, ci\u00f2 fortunatamente, non \u00e8 accaduto ad Enzo Prosperi. Milanese di 61 anni, imprenditore, rovinato dalla cattiva politica e da una giustizia viva solo nell&#8217;astrazione. L&#8217;imprenditore ha deciso di scegliere un modo diverso per affrontare il dolore e la drastica circostanza affidandosi alla comunicazione. Alla forza del messaggio. In che modo? Stando seduto davanti alla facciata laterale del Duomo, in giacca e cravatta, senza disfarsi perci\u00f2 della sua immagine, intraprendendo un dialogo con i passanti. Ai quali racconta la sua triste vicenda. La sua carriera sfortunata, ebbe inizio nel 1989, quando decise di mettersi in proprio creando una societ\u00e0 di produzione di programmi tv e documentari a sfondo medico-scientifico. Con l&#8217;accentuarsi della crisi gli ospedali non promossero pi\u00f9 l&#8217;entrata, da parte dei dipendenti del format, nelle loro strutture. Prosperi fu costretto a chiudere e a vendere l&#8217;azienda. In seguito ebbero inizio le traversie giudiziarie che annientarono la sua carriera. Nonostante una volont\u00e0 mai spenta. Ora l&#8217;imprenditore vive di donazioni ed ha fondato una manifestazione chiamata \u201cRiprendiamoci l&#8217;Italia\u201d, che verr\u00e0 organizzata il prossimo 7 dicembre, generata dopo l&#8217;accaduto, con lo scopo di raccogliere testimonianze portate da altri imprenditori. E nella quale stanziare mezzi utili ad una ripresa del settore.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILANO \u2013 Il suicidio negli ultimi tempi pare essere diventato la via pi\u00f9 risolutiva per gli imprenditori.<\/p>\n","protected":false},"author":22,"featured_media":33057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-33056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33056"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33057"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}