{"id":33179,"date":"2014-05-19T03:55:58","date_gmt":"2014-05-19T01:55:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/abusa-di-una-giovane-disabile-mentale-arrestato-60enne\/"},"modified":"2023-01-17T12:53:41","modified_gmt":"2023-01-17T11:53:41","slug":"14278-abusa-di-una-giovane-disabile-mentale-arrestato-60enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14278-abusa-di-una-giovane-disabile-mentale-arrestato-60enne\/","title":{"rendered":"Abusa di una giovane disabile mentale, arrestato 60enne"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; L&#8217;uomo \u00e8 accusato anche di sequestro di persona.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Per anni aveva molestato quella giovane vicina di casa, disabile mentale, poi l&#8217;ha sequestrata e condotta in una casa che era nella sua disponibilit\u00e0 ed ha abusato di lei. E&#8217; stata la polizia ad arrestare a Reggio Calabria, Domenico Tirinato, 60 anni. All&#8217;uomo \u00e8 stata notificata un&#8217;ordinanza di custodia cautelare in carcere su richiesta della Procura della Repubblica, ed oltre alle molestie e agli abusi sessuali gli viene contestato anche il reato di sequestro di persona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; L&#8217;uomo \u00e8 accusato anche di sequestro di persona.<\/p>\n","protected":false},"author":19,"featured_media":33180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33179"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33180"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}