{"id":33223,"date":"2014-05-20T07:15:11","date_gmt":"2014-05-20T05:15:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/coop-b-si-ricomincia-a-lavorare-mancano-solo-i-nomi-dei-dipendenti\/"},"modified":"2023-01-17T12:53:45","modified_gmt":"2023-01-17T11:53:45","slug":"14301-coop-b-si-ricomincia-a-lavorare-mancano-solo-i-nomi-dei-dipendenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14301-coop-b-si-ricomincia-a-lavorare-mancano-solo-i-nomi-dei-dipendenti\/","title":{"rendered":"Coop B: si ricomincia a lavorare, mancano &#8216;solo&#8217; i nomi dei dipendenti"},"content":{"rendered":"<p>COSENZA &#8211; Solo tre delle nove cooperative hanno consegnato i nominativi dei lavoratori assorbiti. Resta al palo il problema delle retribuzioni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Comune, sindacati e rappresentanti delle aziende appaltatrici hanno firmato ieri l\u2019accordo che regolamenta i servizi municipali affidati alle cooperative sociali di tipo B. A siglare il nuovo corso dei servizi comunali sono stati l\u2019assessore Carmine Manna, il drettore amministrativo Lucio Sconza e il dirigente alla manutenzione Maria Rosaria Mossuto; per i sindacati erano presenti CGIL e CISL con Gianluca Campolongo e Umberto Calabrone. A partire da oggi le cooperative che hanno consegnato ieri la documentazione potrebbero iniziare la propria attivit\u00e0, ovviamente, in continuit\u00e0 con la tipologia di servizio svolto prima dell\u2019appalto. Le altre potranno lavorare solo nel momento in cui presenteranno la lista dei nomi dei dipendenti assunti. Porio, della CGIL, afferma che entro la giornata di oggi gli elenchi saranno ultimati e consegnati in Comune cos\u00ec da poter avviare l&#8217;iter per la sottoscrizione dei contratti. &#8220;Il problema, &#8211; afferma la sindacalista &#8211; \u00e8 che alcune persone sono migrate dal verde al pulimento e quindi i nominativi andavano messi in ordine. Quello che conta \u00e8 che siamo riusciti a reinserirli tutti&#8221;. <strong>Si tratta di 472 persone che guadagneranno tra 400 e 580 euro al mese. Ma lo stipendio non \u00e8 stato, ad oggi, confermato per tutti i dipendenti. Per alcuni, circa 80, non vi \u00e8 ancora alcuna garanzia del raggiungimento delle 20 ore settimanali di lavoro,<\/strong> il che presume un salario di poco pi\u00f9 di 300 euro. I settori coinvolti sono quelli del pulimento e del canile di Donnici per cui, secondo la Porio, &#8220;si potrebbe profilare a breve una soluzione, soprattutto per le 70 persone operative sul pulimento, integrando le ore lavorative del municipio con altre commesse appaltate alla cooperativa&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Solo tre delle nove cooperative hanno consegnato i nominativi dei lavoratori assorbiti. Resta al palo il problema delle retribuzioni.<\/p>\n","protected":false},"author":18,"featured_media":33224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-33223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33223"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33224"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}