{"id":33339,"date":"2014-05-23T08:36:39","date_gmt":"2014-05-23T06:36:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-futuro-delle-cooperative-di-tipo-b\/"},"modified":"2023-01-17T12:54:30","modified_gmt":"2023-01-17T11:54:30","slug":"14365-il-futuro-delle-cooperative-di-tipo-b","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14365-il-futuro-delle-cooperative-di-tipo-b\/","title":{"rendered":"Il futuro delle cooperative di tipo B a Palazzo dei Bruzi"},"content":{"rendered":"<p>COSENZA &#8211; Quindici milioni di euro da destinare alle cooperative e 3 anni di lavoro per tutti i 470 dipendenti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Si \u00e8 concluso ieri a Palazzo dei Bruzi il dibattito aperto sulle cooperative sociali nella precedente seduta del Consiglio comunale. Ad aprire la discussione \u00e8 stato l\u2019Assessore al ramo Carmine Manna. \u201cL\u2019Amministrazione comunale \u2013 ha detto Manna &#8211; sta procedendo all\u2019affidamento dei lotti previsti dal bando di gara. Siamo riusciti ad avviare questo percorso di cambiamento, con l\u2019obiettivo della salvaguardia dei posti di lavoro, 470 unit\u00e0 che abbiamo inserito nel cronoprogramma, elemento fondamentale del nuovo bando di gara. Ulteriore passaggio \u00e8 stato l\u2019incontro con i sindacati in occasione del quale \u00e8 stata regolamentata la ripartizione del personale rispetto alla quale l\u2019Amministrazione comunale non pu\u00f2 entrare nel merito della destinazione. Immediatamente le ditte aggiudicatarie hanno riportato il cronoprogramma con le unit\u00e0 operative; i nominativi sono stati controllati dall\u2019Amministrazione lotto per lotto e si \u00e8 proceduto con le aggiudicazioni. Rispondendo ad una domanda del Consigliere Enzo Paolini che ha chiesto all\u2019assessore di confermare se tutti i lavoratori erano stati assorbiti e se il compenso sar\u00e0 pari a quello che percepivano prima. L\u2019Assessore Manna ha ribadito<strong> l\u2019inserimento per tutte le 470 unit\u00e0, sottolineando che i compensi per otto lotti \u00e8 pressoch\u00e9 identico a prima e che l\u2019unica criticit\u00e0 riguarda il lotto delle pulizie,<\/strong> \u201cma l\u2019Amministrazione \u2013 ha aggiunto &#8211; sta lavorando per colmare il gap esistente\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cOra, per\u00f2, &#8211; ha tuonato il consigliere&nbsp;Marco Ambrogio &#8211; \u00e8 il momento dell\u2019assunzione delle responsabilit\u00e0. Il bando doveva essere annullato per come \u00e8 stato concepito, soprattutto per le decurtazioni operate sullo stipendio dei lavoratori. Va dato atto all\u2019Assessore Manna di essersi adoperato per la risoluzione di questo problema, anche se va detto che alle 15,00 di oggi un solo lotto risultava aggiudicato. Non \u00e8 tutto ok. Resta il nodo del lotto relativo alle pulizie con i 380 euro di stipendio previsti. Il 28 ottobre avevamo garantito pieno appoggio al Sindaco, esigendo per\u00f2 delle rassicurazioni, indicando, inoltre, due precise condizioni: non un posto di lavoro in meno e lo stipendio confermato. Il Sindaco ci rassicur\u00f2. La ripartizione del personale ci va bene, ma come si risolve la questione della decurtazione degli stipendi? <strong>Nei 4 mesi che non si \u00e8 lavorato nel 2013 il Comune ha risparmiato circa 2 milioni di euro. Queste somme potrebbero benissimo essere ripartite e destinate alle cooperative.<\/strong> Insisto pertanto nel ritenere importante la ripartizione delle somme non erogate e la loro redistribuzione perch\u00e9 si tratta di somme che appartenevano alle cooperative\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel corso della discussione \u00e8 intervenuto anche il Sindaco Mario Occhiuto. \u201cProvo un senso di disagio \u2013 ha detto Occhiuto &#8211; mettendomi nei panni di chi sta dall\u2019altra parte. Se fossi dall\u2019altra parte sarei confuso come i lavoratori che sono qui stasera, soprattutto perch\u00e9 qui si dice tutto e il contrario di tutto. Ho scritto due lettere, abbastanza dure, indirizzate ai dirigenti per la sospensione del servizio. Non \u00e8 possibile che si blocchi per un mese un servizio, come la manutenzione del verde o la pulizia negli uffici. <strong>A questo si aggiunga che le cooperative non rappresentano pi\u00f9 la parte pi\u00f9 debole del nostro tessuto sociale perch\u00e9 ci sono lavoratori nei supermercati, tanto per fare un esempio, che non percepiscono lo stipendio da nove mesi. <\/strong>Noi ascoltiamo tutti e non accettiamo le minacce \u2013 ha aggiunto Occhiuto facendo riferimento ad alcune intemperanze del pubblico presente. Siamo qui per rispettare le persone e siamo abituati a non farci intimorire. Quando abbiamo messo mano alle cooperative, abbiamo affrontato le questioni del dissesto e della certificazione antimafia, avviando un percorso di affiancamento con la Prefettura, evitando anche quel commissariamento che, invece, ha colpito altri comuni. Poi abbiamo aggiudicato tutti i lotti con una gara pubblica. Il percorso intrapreso \u2013 ha proseguito Occhiuto \u2013 \u00e8 a vostro vantaggio. Prima l\u2019affidamento diretto di sei mesi era illegittimo. Ora i lavoratori possono contare su tredicesima e quattordicesima. Abbiamo fatto tutto il possibile. Se ci sar\u00e0 la possibilit\u00e0 di aggiungere delle somme, per quello che \u00e8 consentito nelle diverse tipologie di lavoro, sar\u00e0 fatto, cos\u00ec come anche nel lotto della pulizia, un comparto nel quale c\u2019\u00e8 effettivamente stata una riduzione maggiore, se ci saranno le condizioni, aumenteremo i servizi e le ore di lavoro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Quindici milioni di euro da destinare alle cooperative e 3 anni di lavoro per tutti i 470 dipendenti.<\/p>\n","protected":false},"author":22,"featured_media":33340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-33339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33339"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33340"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}