{"id":33361,"date":"2014-05-24T08:08:50","date_gmt":"2014-05-24T06:08:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/fabiana-la-sedicenne-bruciata-viva\/"},"modified":"2023-01-17T12:54:31","modified_gmt":"2023-01-17T11:54:31","slug":"14376-fabiana-la-sedicenne-bruciata-viva","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14376-fabiana-la-sedicenne-bruciata-viva\/","title":{"rendered":"Un anno fa la morte di Fabiana, corteo per la sedicenne bruciata viva"},"content":{"rendered":"<p>CORIGLIANO CALABRO &#8211; Alcune centinaia di ragazzi stanno partecipando a Corigliano Calabro al corteo organizzato in occasione del primo anniversario dell&#8217;omicidio di Fabiana Luzzi, la sedicenne uccisa dal fidanzato che ne bruci\u00f2 il corpo quando la giovane era ancora viva.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tutti i ragazzi hanno una rosa bianca in mano. In testa al corteo uno striscione con la scritta: &#8221;Vogliamo ricordarti com&#8217;eri, pensare che ancora vivi. Vogliamo pensare che ancora ci ascolti, che come allora ci sorridi&#8221;. La frase riportata nello striscione dedicato a Fabiana Luzzi \u00e8 tratta da una canzone di Carmen Consoli, &#8220;Canzone per un&#8217;amica&#8221;. In testa al corteo, che si sta svolgendo in modo silenzioso, ci sono i genitori di Fabiana, Mario e Rosa, abbracciati al loro arrivo dai compagni della sedicenne, che come il padre e la madre della ragazza si sono abbandonati ad un pianto dirotto. All&#8217;inizio anche uno striscione del &#8221;Centro antiviolenza Fabiana Luzzi&#8221;, costituito a Corigliano Calabro dopo l&#8217;uccisione della sedicenne. <strong>Un giovane, che precede di poco i compagni, porta in mano un bouquet di rose bianche che sar\u00e0 lasciato nel punto in cui la sedicenne fu uccisa dal fidanzato, Davide Morrone, oggi diciottenne, condannato in primo grado a 22 anni di reclusione.<\/strong> Il prefetto di Cosenza, Gianfranco Tomao, stamattina ha incontrato i genitori di Fabiana nella loro abitazione per rinnovare loro la sua solidariet\u00e0. Il corteo \u00e8 stato sospeso per qualche minuto a causa di un malore avvertito da una delle tre sorelle della vittima che pare abbia accusato un calo di pressione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO CALABRO &#8211; Alcune centinaia di ragazzi stanno partecipando a Corigliano Calabro al corteo organizzato in occasione del primo anniversario dell&#8217;omicidio di Fabiana Luzzi, la sedicenne uccisa dal fidanzato che ne bruci\u00f2 il corpo quando la giovane era ancora viva.<\/p>\n","protected":false},"author":22,"featured_media":33362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-33361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33361"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33362"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}