{"id":33363,"date":"2014-05-24T08:25:13","date_gmt":"2014-05-24T06:25:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ndrangheta-al-nord-il-grande-aracri-di-cutro-a-piacenza-sei-arresti\/"},"modified":"2023-01-17T12:54:31","modified_gmt":"2023-01-17T11:54:31","slug":"14377-ndrangheta-al-nord-il-grande-aracri-di-cutro-a-piacenza-sei-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14377-ndrangheta-al-nord-il-grande-aracri-di-cutro-a-piacenza-sei-arresti\/","title":{"rendered":"&#8216;Ndrangheta al Nord: il Grande Aracri di Cutro a Piacenza, cinque arresti"},"content":{"rendered":"<p>PIACENZA &#8211; E&#8217; scattata all&#8217;alba l&#8217;ultima fase dell&#8217;operazione Grande Drago.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I carabinieri della compagnia di Fiorenzuola e del nucleo investigativo di Piacenza hanno condotto un\u2019imponente attivit\u00e0 per contrastare il potere occulto della \u2018ndrangheta calabrese nella provincia piacentina. Sono stati arrestati cinque presunti affiliati alla cosca Grande Aracri di Cutro accusati di estorsioni, detenzione porto illegale di armi comuni da sparo e da guerra, detenzione e vendita stupefacenti. Nelle prime ore del mattino di oggi, nelle province di Piacenza, Cremona, e Crotone, i carabinieri hanno eseguito cinque ordinanze di custodia cautelare nei confronti di altrettanti affiliati al citato sodalizio criminoso che, dopo le condanne inflitte dal Tribunale di Piacenza e Corte d\u2019Appello di Bologna, avevano presentato appello in Cassazione ove, di recente, sono state, in maniera definitiva, inflitte le pene. Tre degli arrestati erano nel Piacentino, uno \u00e8 stato raggiunto dall\u2019ordinanza a Cremona e il quinto a Cutro.<\/p>\n<p>  Cos\u00ec Francesco Lamanna 53 anni di Cutro e residente Cremona \u00e8 stato condannato a 8 mesi; Antonio Villirillo, 57 anni di Cutro e residente a Monticelli d&#8217;Ongina (Piacenza), \u00e8 stato condannato a 2 anni e 2 mesi di reclusione; Gennaro Pascale, 55 anni di Cutro e residente a Monticelli d&#8217;Ongina \u00e8 stato condannato a 3 anni e un mese; Gianluca Amato, 41enne di Villarosa (Enna) e anche lui residente Monticelli d&#8217;Ongina \u00e8 stato condannato a 2 anni di reclusione; Alfonso Mesoraca, 48enne di Cutro e sempre residente a Monticelli d&#8217;Ongina, \u00e8 stato condannato a 3 anni e 2mesi di reclusione. Gli arrestati sono ora in carcere tra Piacenza, Cremona e Crotone. Grande Drago &#8220;fu la prima operazione coordinata dalla Dda di Bologna &#8211; ha sottolineato il colonnello dei carabinieri Luca Pietranera &#8211; che dimostr\u00f2 le infiltrazioni delle cosche nell&#8217;Emilia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIACENZA &#8211; E&#8217; scattata all&#8217;alba l&#8217;ultima fase dell&#8217;operazione Grande Drago.<\/p>\n","protected":false},"author":22,"featured_media":33364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33363"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33364"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}