{"id":33414,"date":"2014-05-26T16:32:12","date_gmt":"2014-05-26T14:32:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cittadini-boicottano-le-urne-elezioni-non-valide-per-la-seconda-volta-a-roccaforte\/"},"modified":"2023-01-17T12:54:34","modified_gmt":"2023-01-17T11:54:34","slug":"14404-cittadini-boicottano-le-urne-elezioni-non-valide-per-la-seconda-volta-a-roccaforte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14404-cittadini-boicottano-le-urne-elezioni-non-valide-per-la-seconda-volta-a-roccaforte\/","title":{"rendered":"Un unico candidato, cittadini boicottano le urne. Elezioni nulle a Roccaforte"},"content":{"rendered":"<p>ROCCAFORTE DEL GRECO (RC) &#8211; Per la seconda volta consecutiva a Roccaforte del Greco, nel reggino, le elezioni per il rinnovo del consiglio comunale sono andate deserte.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La tornata elettorale \u00e8 stata annullata perch\u00e8 non si \u00e8 raggiunto il quorum del 50% dei votanti. Il 27 maggio 2013 la percentuale dei votanti era stata dell&#8217; 11,68% e l&#8217;allora candidato sindaco unico, Giuseppe Minnella, con la lista civica Roccaforte Rinasci, aveva ricevuto 54 voti. Anche quest&#8217;anno c&#8217;era un unico candidato sindaco, Domenico Penna, a capo della lista civica &#8216;To Vun\u00ec&#8217; il quale ha ottenuto 226 preferenze. I votanti per\u00f2 sono stati 250 dei 511 aventi diritto pari al 48,92%. Anche in questo caso, cos\u00ec come era accaduto l&#8217;anno scorso, sar\u00e0 nominato un commissario che provveder\u00e0 alla gestione del Comune in attesa della prossima tornata amministrativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROCCAFORTE DEL GRECO (RC) &#8211; Per la seconda volta consecutiva a Roccaforte del Greco, nel reggino, le elezioni per il rinnovo del consiglio comunale sono andate deserte.<\/p>\n","protected":false},"author":22,"featured_media":33415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33414"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33415"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}