{"id":3342,"date":"2012-09-08T10:37:20","date_gmt":"2012-09-08T08:37:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3342"},"modified":"2023-01-17T13:35:53","modified_gmt":"2023-01-17T12:35:53","slug":"405-torano-c-corbelli-accusa-gli-amministratori-padroni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/405-torano-c-corbelli-accusa-gli-amministratori-padroni\/","title":{"rendered":"Torano C., Corbelli accusa gli amministratori &#8220;padroni&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: Times;\"><strong>TORANO CASTELLO \u2013<\/strong> I \u201cpadroni\u201d del Comune. A Torano Castello, centro della Media Valle del Crati, distante una manciata di km da Cosenza, \u00e8, da tempo, in atto un quotidiano attacco alle regole del buon governo e della democrazia. <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: Times;\">L\u2019inquietante denuncia viene fatta da Franco Corbelli, carismatico leader del noto Movimento \u201cDiritti Civili\u201d, che di guerre contro le ingiustizie e battaglie a difesa del sociale ne ha fatto, da oltre vent\u2019anni, una missione. Nel mirino di Corbelli, sono finiti il sindaco Sabatino Cariati e un suo fedelissimo assessore Guido Fazio. I due, secondo lo stesso leader del movimento, da tempo \u201cspadroneggiano\u201d sul territorio, gestendo la cosa pubblica in maniera \u201cpersonale\u201d, senza tenere conto del rispetto della democrazia. Corbelli, infatti, dichiara che l\u2019assessore Guido Fazio, con il \u201cplacet\u201d del sindaco, ricopre contemporaneamente sette incarichi di livello istituzionale, nonch\u00e9 \u00e8 titolare di un\u2019impresa edile che lavora nel territorio comunale della sua Torano. Franco Corbelli, spiega che Guido Fazio \u00e8 \u00abconsigliere comunale, assessore all\u2019urbanistica, ingegnere progettista, direttore dei lavori, responsabile tecnico e della sicurezza, nonch\u00e9 progettista del nuovo cimitero\u00bb. Un uomo pieno di risorse, verrebbe da dire. \u00abMacch\u00e8 \u2013 insiste il leader di \u201cDiritti Civili \u2013 gli incarichi che gestisce l\u2019assessore sono figli di una spietata politica accentrista e plurimandataria. Non per ultimo \u2013 prosegue \u2013 \u00e8 stato nominato dal Comune tutor di un gruppo di giovani per un progetto tra l\u2019amministrazione comunale e il centro per l\u2019impiego. Basta pensare che quest\u2019amministratore \u2013 fa rilevare \u2013 autorizza lavori edili nel Comune, quale assessore all\u2019Urbanistica e li esegue con la sua impresa, di cui \u2013 ricorda Corbelli \u2013 \u00e8 direttore del cantiere e responsabile della sicurezza\u00bb. Queste anomalie Franco Corbelli le ha sempre segnalate alla procura della Repubblica e alla prefettura di Cosenza. Pi\u00f9 di una volta, infatti, \u00e8 stato ricevuto sia dal procuratore capo Dario Granieri, che dal prefetto Raffaele Cannizzaro. Ai due \u201csimboli\u201d dello Stato e della legalit\u00e0 ha denunciato gli atti illegittimi del sindaco e dell\u2019assessore. Corbelli ha caricato anche altro. \u00abPer biechi interessi personali \u2013 ha sottolineato \u2013 nerl giro di poco tempo \u00e8 stata cambiata la destinazione d\u2019uso ai posti auto di un\u2019immobile dell\u2019assessore Fazio, trasformati in un bar di propriet\u00e0 dello stesso amministratore e in magazzini ad uso commerciale, oggi tutti affittati\u00bb. Le insistenti segnalazioni di Corbelli hanno portato la Procura ad aprire un\u2019inchiesta, delegando i carabinieri della locale stazione, coordinati dal maresciallo Antonio Di Vasto e i militari della Compagnia di Rende, ad avviare approfondite e certosine indagini in tal senso. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORANO CASTELLO \u2013 I \u201cpadroni\u201d del Comune. A Torano Castello, centro della Media Valle del Crati, distante una manciata di km da Cosenza, \u00e8, da tempo, in atto un quotidiano attacco alle regole del buon governo e della democrazia.<\/p>\n","protected":false},"author":22,"featured_media":608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-3342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3342"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/608"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}