{"id":33497,"date":"2014-05-29T03:56:17","date_gmt":"2014-05-29T01:56:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/beni-culturali-e-paesaggistici-giornata-informativa-per-la-loro-salvaguardia\/"},"modified":"2023-01-17T12:54:40","modified_gmt":"2023-01-17T11:54:40","slug":"14448-beni-culturali-e-paesaggistici-giornata-informativa-per-la-loro-salvaguardia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14448-beni-culturali-e-paesaggistici-giornata-informativa-per-la-loro-salvaguardia\/","title":{"rendered":"Beni culturali e paesaggistici, giornata informativa per la loro salvaguardia"},"content":{"rendered":"<p>ROCCELLETTA DI BORGIA (CZ) &#8211; Un\u2019incontro tecnico nella sala conferenze del Parco Scolacium per discutere della gestione dell\u2019emergenza e salvaguardia del patrimonio culturale.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una giornata informativa alla Direzione regionale per i Beni culturali e paesaggistici della Calabria, nel corso della quale si \u00e8 parlato dell&#8217;Umbria, dell\u2019Abbruzzo, dell\u2019Emilia e prima ancora dell\u2019Irpinia; emergenze che, negli ultimi decenni hanno messo in luce un\u2019urgenza non pi\u00f9 rinviabile, quella di una rete capillare che possa fronteggiare simili situazioni e salvaguardare i beni culturali. Una sfida che il MiBACT ha deciso di affrontare coinvolgendo le Direzioni regionali, e coordinando un programma apposito insieme a numerosi soggetti e istituzioni, vari livelli di governo, oltre al volontariato e al terzo settore. La giornata dei lavori organizzata a Roccelletta di Borgia dalla Direzione regionale per i beni culturali e paesaggistici della Calabria, moderata dal responsabile Salvatore Patamia, ha potuto contare su un nutrito parterre di convenuti, ma prima ancora di alcuni illustri relatori, a partire dal prefetto Fabio Carapezza Guttuso che ha illustrato l\u2019attuale situazione e le attivit\u00e0 dell\u2019Unit\u00e0 di crisi \u2013 coordinamento nazionale: \u201cCon le emergenze de L\u2019Aquila, di Assisi, ma anche di Mormanno, si \u00e8 imposta la necessit\u00e0 di un dialogo che sia il pi\u00f9 tempestivo possibile, che permetta di muoversi correttamente in quella che \u00e8 la galassia dell\u2019intervento\u201d. Rispettare i proprietari dei beni, conoscere la loro esatta collocazione e descrizione, ipotizzare centri di raccolta momentanea, quantificare subito la portata dei danni per riuscire a intercettare altrettanto velocemente i fondi straordinari, \u201cperch\u00e9 l\u2019emergenza rischia di essere superata sempre da un\u2019altra emergenza\u201d. Sono alcuni dei momenti chiave dell\u2019intervento che non si limita all\u2019immediato post-calamit\u00e0, ma che \u00e8 fondamentale anche nel momento della ricostruzione: \u201cDi fronte alle macerie \u2013 ha spiegato Carapezza \u2013 che si fa? Non sono tutte uguali e bisogna sapere se l\u00ec c\u2019\u00e8 un Cimabue\u201d. A illustrare la struttura dell\u2019Uccn, con le relative unit\u00e0 di rilievo dei danni al patrimonio, di coordinamento tecnico degli interventi di messa in sicurezza, dei depositi temporanei e del laboratorio di pronto intervento, \u00e8 stato Paolo Iannelli: \u201cL\u2019emergenza si gestisce se si gestisce gi\u00e0 l\u2019ordinario\u201d, ha affermato, ribadendo come nulla pu\u00f2 essere lasciato al caso. Un esempio pratico lo ha riportato quindi il soprintendente per i Beni e le attivit\u00e0 culturali e paesaggistiche di Cosenza Catanzaro e Crotone Luciano Garella: \u201cIl sisma di Mormanno del 2012 ha dimostrato la necessit\u00e0 di lucidit\u00e0 nell\u2019intervento \u2013 ha detto -, insieme alla definizione di procedure pi\u00f9 determinate\u201d. Condizioni fondamentali per una terra come la Calabria \u201cche in quanto a dissesto idrogeologico non si fa mancare nulla\u201d. \u201cDopo quanto accaduto a Soverato, Catanzaro ha posto un\u2019attenzione particolare alle situazioni a rischio, ma non \u00e8 abbastanza\u201d, ha ammesso il vice prefetto di Catanzaro Osvaldo Caccuri che si \u00e8 soffermato proprio sul rapporto sempre pi\u00f9 funzionale e meno gerarchico delle Prefetture, che lavorano a stretto contatto con le altre strutture. Basilari per la messa in pratica di ogni operazione sono poi gli apporti dei Vigili del fuoco e dei Carabinieri, le cui attivit\u00e0 in merito sono state esposte rispettivamente da Roberto Fasano e dal maresciallo Francesco Leone. Altro ruolo importante \u00e8 quello della Cei in quanto proprietaria dei beni culturali ecclesiastici, sulla cui archiviazione informatizzata si \u00e8 soffermato Paolo Martino. A concludere le relazioni, seguite da un vivace dibattito con i presenti, ci sono stati gli interventi di Paolo Scarpitti, sul ruolo degli Istituti centrali del MiBACT, e di Antonella Negri, che ha definito la primaria importanza della conoscenza della consistenza e dislocazione del patrimonio culturale colpito: cruciale pu\u00f2 essere la parte giocata da \u201cVincoliinrete.beniculturali.it\u201d, il progetto online che integra i dati dei Sistemi informativi Carta del rischio, Beni tutelati, Sitap e Sigec Web, con funzionalit\u00e0 di ricerca dei beni sia di tipo alfanumerico che cartografico, perfetta per la localizzazione degli stessi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROCCELLETTA DI BORGIA (CZ) &#8211; Un\u2019incontro tecnico nella sala conferenze del Parco Scolacium per discutere della gestione dell\u2019emergenza e salvaguardia del patrimonio culturale.<\/p>\n","protected":false},"author":22,"featured_media":33498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33497"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33498"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}