{"id":33593,"date":"2014-06-03T08:33:54","date_gmt":"2014-06-03T06:33:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/imprese-prestiti-e-tassi-d-interesse-maglia-nera-a-crotone\/"},"modified":"2023-01-17T12:54:46","modified_gmt":"2023-01-17T11:54:46","slug":"14496-imprese-prestiti-e-tassi-d-interesse-maglia-nera-a-crotone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14496-imprese-prestiti-e-tassi-d-interesse-maglia-nera-a-crotone\/","title":{"rendered":"Imprese, prestiti e tassi d&#8217;interesse: maglia nera a Crotone"},"content":{"rendered":"<p>CROTONE &#8211; Il \u201ccaro-denaro\u201d penalizza le aziende di piccola dimensione: i tassi medi di interesse applicati ai prestiti fino a 250mila euro infatti, raggiungono il 4,75%.<\/p>\n<p>  <!--more-->  <\/p>\n<p>E addirittura i tassi, raggiungono punte record in Calabria e in Sardegna: <strong>Crotone<\/strong> e&#8217; &#8216;maglia nera&#8217; per i <strong>tassi<\/strong> piu&#8217; alti che toccano l&#8217;<strong>8,67%<\/strong> seguita da Olbia-Tempio con il 7,83% e da Carbonia-Iglesias con il 7,79%. Sul versante opposto della classifica, la provincia autonoma di Bolzano fa registrare tassi di interesse del 3,81%, di poco inferiore al 4,11% applicato a Cuneo e del 4,26% applicato a Udine. E&#8217; quanto emerge da una studio della <strong>Confartigianato<\/strong> Emilia Romagna, secondo cui il divario Nord-Sud si riscontra anche nella quantita&#8217; di finanziamenti erogati: la diminuzione del credito ha colpito in particolare le imprese con meno di 20 addetti e la situazione peggiore riguarda il Molise, dove, tra febbraio 2013 e febbraio 2014, lo stock di prestiti alle imprese e&#8217; calato dell&#8217;11,7%. Seguono Umbria e Marche, con una diminuzione del 7,8%, e la Sicilia (-7%). In questo specifico segmento, le imprese con meno di 20 addetti, l&#8217;Emilia Romagna si posiziona al 14esimo posto con un calo del -7,8%. A livello provinciale, il calo piu&#8217; vistoso dei finanziamenti interessa le piccole imprese di Isernia (-21,3% tra febbraio 2013 e febbraio 2014), seguite da quelle di Caltanissetta ( &#8211; 10,9%) e da quelle di Biella (-10%). A &#8216;soffrire&#8217; le difficolta&#8217; di accesso al credito sono soprattutto le piccole imprese del settore manifatturiero: secondo il rapporto di Confartigianato, infatti, nel I trimestre 2014, a denunciare problemi e&#8217; il 18,1% delle aziende manifatturiere con meno di 50 addetti, a fronte di una quota dell&#8217;11,3% di aziende manifatturiere di media dimensione e del 12% di grandi imprese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Il \u201ccaro-denaro\u201d penalizza le aziende di piccola dimensione: i tassi medi di interesse applicati ai prestiti fino a 250mila euro infatti, raggiungono il 4,75%.<\/p>\n","protected":false},"author":22,"featured_media":33594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33593"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33594"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}