{"id":33616,"date":"2014-06-04T07:08:07","date_gmt":"2014-06-04T05:08:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/stupro-di-gruppo\/"},"modified":"2023-01-17T12:54:48","modified_gmt":"2023-01-17T11:54:48","slug":"14508-stupro-di-gruppo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14508-stupro-di-gruppo\/","title":{"rendered":"Stupro di gruppo e rapina con pestaggio, arancia meccanica a Montalto"},"content":{"rendered":"<p>MONTALTO UFFUGO &#8211; Erano ubriachi quando, esattamente un mese fa, bloccarono l&#8217;auto su cui viaggiava la loro vittima.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tre giovani sono stati arrestati ieri sera dai militari della stazione di Montalto Uffugo. Sono poco pi\u00f9 che ventenni, ma su di loro pesano accuse gravissime. Intorno alla mezzanotte, il 3 Maggio, in preda ai fumi dell&#8217;alcool i ragazzi avrebbero assaltato una vettura minacciando di morte il conducente e palpeggiando con insistenza nelle parti intime la donna al suo fianco. La malcapitata, una trentaseienne residente a Lappano, sarebbe poi stata costretta ad allontanarsi dall&#8217;auto dell&#8217;amico per appartarsi con uno dei tre che l&#8217;avrebbe violentata mentre gli amici erano intenti a sfondare la porta di casa e pestare il suo convivente, un 48enne cosentino. Gli autori della triste vicenda sono tutti di Montalto Uffugo. Si tratta di Paolo Bruno 23enne, Valentino e Marco Di Biase di 22 e 27 anni. I primi due sono stati posti agli arresti domiciliari, mentre Marco Di Biase, il quale si sarebbe allontanato con la donna nel momento in cui gli altri stavano saccheggiando l&#8217;appartamento del compagno della vittima, \u00e8 stato tradotto presso la casa circondariale di via Popilia. I tre sono accusati di violenza sessuale di gruppo, sui&nbsp; pi\u00f9 giovani pende il reato di rapina, mentre al Di Biase (sottoposto al test del Dna) viene anche contestato lo stupro. Il bottino raccimolato dai malviventi era composto da qualche bottiglia di vino e dalla borsa della donna che \u00e8 stata intercettata dai carabinieri ancora seminuda ed in pieno stato di agitazione a pochi passi dall&#8217;appartamento. I giovani hanno ammesso le proprie responsabilit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO &#8211; Erano ubriachi quando, esattamente un mese fa, bloccarono l&#8217;auto su cui viaggiava la loro vittima.<\/p>\n","protected":false},"author":18,"featured_media":33617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-33616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33616"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33617"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}