{"id":33697,"date":"2014-06-06T09:20:47","date_gmt":"2014-06-06T07:20:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/porte-rotte-e-finestre-aperte-al-reparto-malattie-infettive-protestano-i-pazienti\/"},"modified":"2023-01-17T12:54:54","modified_gmt":"2023-01-17T11:54:54","slug":"14549-porte-rotte-e-finestre-aperte-al-reparto-malattie-infettive-protestano-i-pazienti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14549-porte-rotte-e-finestre-aperte-al-reparto-malattie-infettive-protestano-i-pazienti\/","title":{"rendered":"Porte rotte e finestre aperte al reparto Malattie Infettive, pazienti in protesta"},"content":{"rendered":"<p>CATANZARO &#8211; Sono numerose le proteste che vengono segnalate da parte dei familiari e dei malati del reparto di malattie infettive dell&#8217;ospedale di Catanzaro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nella struttura, infatti, ci sono da diverso tempo ormai, porte rotte e da oggi, anche a causa delle temperature elevate, i sanitari sono costretti a lavorare con gli ambienti aperti. Di conseguenza i pazienti si dicono preoccupati perch\u00e8 la situazione in cui vivono nel reparto, \u00e8 ritenuta ad <strong>alto rischio<\/strong> considerato che ci sono pazienti con malattie infettive e l&#8217;apertura di una porta rischia di creare <strong>condizioni di contagio<\/strong>. I familiari dei pazienti ricoverati, inoltre, hanno chiesto al personale sanitario di intervenire per porre rimedio alla situazione ma al momento non sono state trovate soluzioni. Una situazione di disagio, quella vissuta nel reparto, che \u00e8 stata pi\u00f9 volte segnalata alla direzione sanitaria ma al momento non sono stati predisposti interventi di manutenzione. Inoltre, per accedere al reparto ci sono due ascensori ma al momento ne funziona solamente uno, mentre l&#8217;altro \u00e8 guasto da ben nove anni. Una paziente ha diffuso una nota nella quale evidenzia che &#8220;nel reparto di malattie infettive non sono rese funzionanti quelle misure precauzionali che, pure, erano state previste. Solo a titolo esemplificativo si evidenzia che le porte non sono a tenuta stagna e non consentono il necessario isolamento. Il sistema di areazione spesso non \u00e8 funzionante accentuando l&#8217;effetto serra degli ambienti&#8221;. &#8220;Ci sono poi &#8211; conclude la paziente &#8211; poltrone rotte, veneziane inservibili, pareti a vetro prive di qualsiasi riparo dalla luce anche per quei malati che avrebbero bisogno di penombra per riposare. Allo stesso tempo voglio ringraziare tutto il personale che, con professionalit\u00e0 e spirito umano, svolgono il loro lavoro quotidianamente. Personale medico e paramedico che mi ha consentito di superare la mia malattia solamente grazie al loro spirito di sacrificio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Sono numerose le proteste che vengono segnalate da parte dei familiari e dei malati del reparto di malattie infettive dell&#8217;ospedale di Catanzaro.<\/p>\n","protected":false},"author":19,"featured_media":33698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33697"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33698"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}