{"id":33737,"date":"2014-06-07T10:10:05","date_gmt":"2014-06-07T08:10:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cavallo-di-ritorno-si-ribella-per-un-furgone\/"},"modified":"2023-01-17T12:54:56","modified_gmt":"2023-01-17T11:54:56","slug":"14569-cavallo-di-ritorno-si-ribella-per-un-furgone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14569-cavallo-di-ritorno-si-ribella-per-un-furgone\/","title":{"rendered":"Racket: si ribella, rifiuta il &#8216;cavallo di ritorno&#8217; e fa arrestare estorsore"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Commerciante reggino reagisce alle intimidazioni.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Un commerciante di Reggio Calabria ha subito il furto del furgone, si \u00e8 posto alla ricerca del mezzo e si \u00e8 rivolto ad alcuni rom che riteneva potessero fornirgli notizie utili. Quando gli sono stati chiesti 300 euro per ottenere la restituzione del furgone, si \u00e8 rivolto ai carabinieri ed ha fatto arrestare uno dei responsabili, Domenico Berlingieri, di 34 anni, nei confronti del quale \u00e8 stata eseguita un&#8217;ordinanza di custodia cautelare in carcere emessa dal Gip.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Commerciante reggino reagisce alle intimidazioni.<\/p>\n","protected":false},"author":22,"featured_media":33738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-33737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=33737"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=33737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=33737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=33737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}