{"id":3375,"date":"2012-09-10T06:29:43","date_gmt":"2012-09-10T04:29:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3375"},"modified":"2023-01-17T13:35:56","modified_gmt":"2023-01-17T12:35:56","slug":"439-sotto-il-vestito-il-ritorno-della-lingerie-hot","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/439-sotto-il-vestito-il-ritorno-della-lingerie-hot\/","title":{"rendered":"Sotto il vestito il ritorno della lingerie hot"},"content":{"rendered":"<p style=\"text-align: justify;\">Deve essere per via del Burlesque, un boom inatteso e in continua espansione. Si moltiplicano i corsi, non solo nelle grandi citt\u00e0. Seminari, allenamenti in palestra, reality show e anche lezioni private. Tutte come Dita Von Teese, la reginetta dello streap tease vintage. Gli stilisti, le case di moda, i creativi prendono nota. Ed ecco che in vetrina arrivano ondate di biancheria intima retro, ma soprattutto bustini e corsetti, simil-lingerie. Metti sopra quello che portavi sotto.<\/p>\n<p style=\"text-align: justify;\">La tendenza dell&#8217;autunno imminente vira anche sul sadomaso: un&#8217;invasione di capi in pelle nera o in latex capricciosamente trasgressivi, aggressivi, allusivi, in linea con il libro dell&#8217;estate, Cinquanta sfumature di grigio (Mondadori), letteratura erotica della porta accanto. Se fino a poco tempo fa certi articoli erano in vendita solo in boutique di intimo alte di gamma, oggi la lingerie genere (quasi) sexy shop \u00e8 disponibile anche nelle grandi catene come Yamamay, Intimissimi o Golden Point: la seduzione si sta democratizzando, la sensualit\u00e0 diventa un&#8217;opzione di massa. E la moda di stagione propende per lo stile educazione severa.<\/p>\n<p style=\"text-align: justify;\">Il guardaroba diventa hot in tutte le ore del giorno. Se Karl Kraus sosteneva che &#8220;l&#8217;intelligenza \u00e8 come la biancheria intima, tutti dovremmo usarla ma nessuno dovrebbe esibirla&#8221;, da almeno un quarto di secolo le regole sono cambiate. Erano gli anni Novanta quando Madonna con Jean Paul Gaultier e poi Dolce &amp; Gabbana sdoganarono la lingerie facendone un capo da portare a vista e non certo da occultare, anzi.<\/p>\n<div style=\"text-align: justify;\">&nbsp;<\/div>\n<p style=\"text-align: justify;\">Tutte esibizioniste, tutte strizzate in lacci e lacciuoli, compresse in stecche, scolpite modello clessidra, tutte supersexy anche se i ganci sul dorso spezzano il respiro. E soprattutto tutte in gu\u00eapiere: come al solito a indicare la strada sono le star, puntualmente in corsetto, in corpetto, in bustino con o senza borchie: Rihanna addirittura con gli aculei di metallo, stringatissime in neoprene anche l&#8217;immancabile Lady Gaga, Shakira, Kylie Minogue, sempre molto fetish quando salgono su un palco, meglio se con un tocco gothic. Se il nero \u00e8 il colore base e il pi\u00f9 hard specie in pelle o in ecopelle, fanno capolinea anche il silver e il bianco, che ha un effetto spiazzante, abbinando candidi e virginali inserti di pizzo a un look decisamente non da educanda. Il pi\u00f9 chic \u00e8 certamente il color carne, tra i pi\u00f9 richiesti per balconcini, guaine, coulottes alte in vita, sottovesti, perizoma, stringivita, body, bustier, corsetti e persino per i baby doll, un capo di biancheria arcaico che il Burlesque ha resuscitato dalla naftalina.<\/p>\n<p style=\"text-align: justify;\">Katy Perry ha fatto scuola posando in simil-lingerie nude sulla copertina di Rolling Stone. Niente di nuovo sotto il sole: nel lontano 1885, nascosto dietro lo pseudonimo Lila Biscuit, un ventiduenne Gabriele D&#8217;Annunzio versione cronista mondano osservava che il lusso per la biancheria stava diventando addirittura rovinoso: &#8220;Le pi\u00f9 squisite eleganze son profuse in quei leggeri vestiti che, nella lor trasparenza, prendono il profumo e il dolce color roseo della cute femminile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deve essere per via del Burlesque, un boom inatteso e in continua espansione. Si moltiplicano i corsi, non solo nelle grandi citt\u00e0. Seminari, allenamenti in palestra, reality show e anche lezioni private. Tutte come Dita Von Teese, la reginetta dello streap tease vintage. Gli stilisti, le case di moda, i creativi prendono nota. Ed ecco [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,92,5],"tags":[],"class_list":["post-3375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-ck10-moda-tendenze","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3375"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/674"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}