{"id":34004,"date":"2014-06-17T03:39:16","date_gmt":"2014-06-17T01:39:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/dopo-4-anni-fermato-l-assassino-di-yara-gambirasio\/"},"modified":"2023-01-17T12:55:24","modified_gmt":"2023-01-17T11:55:24","slug":"14707-dopo-4-anni-fermato-l-assassino-di-yara-gambirasio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14707-dopo-4-anni-fermato-l-assassino-di-yara-gambirasio\/","title":{"rendered":"Dopo 4 anni fermato &#8216;Ignoto 1&#8217;, il presunto assassino di Yara Gambirasio"},"content":{"rendered":"<p>BERGAMO &#8211; A trovare il corpo della tredicenne, dopo tre mesi di ricerche dalla sua scomparsa, nascosto tra le sterpaglie, fu un aeromodellino caduto in un campo incolto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;uomo che scopri il cadavere di Yara, vide prima dei vestiti: &#8220;sembravano stracci &#8211; disse &#8211; poi per\u00f2 avvicinandomi ho visto i piedi&#8221;.&nbsp;Dopo anni di indagini dunque, l&#8217;assassino di Yara, 13 anni, scomparsa il 26 novembre da Brembate Sopra, in provincia di Bergamo, \u00e8 il figlio illegittimo di un autista scomparso. La svolta ieri pomeriggio quando \u00e8 arrivata la notizia del fermo di Massimo Giuseppe Bossetti ritenuto l&#8217;omicida di Yara, incastrato dal Dna. A comunicarla il ministro dell&#8217;interno, Angelino Alfano: \u201cLe forze dell\u2019ordine, d\u2019intesa con la magistratura, hanno individuato l\u2019assassino di Yara Gambirasio\u201c. L&#8217;uomo ha 44 anni, \u00e8 sposato, ha tre figli, \u00e8 incensurato e fa il muratore, e forse aveva lavorato proprio nel cantiere dove i cani molecolari fiutarono per la prima volta &#8220;qualcosa&#8221; indirizzando gli inquirenti sul posto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong> &#8216;Ignoto 1&#8217; ora ha un volto e un nome<\/strong><\/p>\n<p>Prelevato da casa e interrogato in caserma, non ha risposto a nessuna delle domande del pm ma anzi, ha dapprima respinto le accuse, e poi si \u00e8 avvalso della facolt\u00e0 di non rispondere come ha riferito l\u2019avvocato d\u2019ufficio Silvia Gazzetti. Al figlio illeggittimo dell&#8217;autista , si \u00e8 arrivati dopo che gli inquirenti hanno individuato la madre, che aveva avuto una storia con l\u2019autista Giuseppe Guerinoni, morto nel \u201999 e il cui Dna, era stato prelevato dopo la riesumazione e cui era riconducibile il profilo genetico trovato sugli slip di Yara. Il cerchio intorno a Bossetti ha iniziato a stringersi quando alla donna \u00e8 stato fatto il tampone. I test sono stati ripetuti due volte per avere la certezza che fosse proprio lei, la madre di Ignoto 1, e Guerinoni il padre. All\u2019anziana i carabinieri erano arrivati sulla base di alcune voci di paese che le avevano attribuito una frequentazione negli anni Sessanta con Giuseppe Guerinoni. Per individuare l\u2019assassino di Yara in questi anni sono stati prelevati oltre 18mila campioni genetici e non solo in provincia di Bergamo. E gli inquirenti sono sicuri: &#8220;la compatibilit\u00e0 non lascia dubbi&#8221; perch\u00e8 \u00e8 del 99,99999987%. Gli investigatori hanno anche sequestrato una Volvo station wagon e un furgoncino Peugeot Ranch di colore chiaro. Inoltre, pare inoltre che il cellulare di Bossetti \u00e8 risultato tra quelli che avevano impegnato la cella della zona dove \u00e8 stato trovato il cadavere, nell\u2019ora in cui sarebbe avvenuto l\u2019omicidio e che determinerebbe la presenza dell\u2019uomo proprio l\u00ec e nel momento in cui Yara veniva ammazzata.Bossetti, dopo l&#8217;interrogatorio l&#8217;uomo, \u00e8 stato trasferito in carcere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BERGAMO &#8211; A trovare il corpo della tredicenne, dopo tre mesi di ricerche dalla sua scomparsa, nascosto tra le sterpaglie, fu un aeromodellino caduto in un campo incolto.<\/p>\n","protected":false},"author":19,"featured_media":34005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-34004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34004"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34005"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}