{"id":34088,"date":"2014-06-19T05:15:15","date_gmt":"2014-06-19T03:15:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ospedale-di-cosenza-occhiuto-passi-dalle-parole-ai-fatti-dopo-la-visita-prescriva-la-cura\/"},"modified":"2023-01-17T12:55:29","modified_gmt":"2023-01-17T11:55:29","slug":"14753-ospedale-di-cosenza-occhiuto-passi-dalle-parole-ai-fatti-dopo-la-visita-prescriva-la-cura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14753-ospedale-di-cosenza-occhiuto-passi-dalle-parole-ai-fatti-dopo-la-visita-prescriva-la-cura\/","title":{"rendered":"Ospedale di Cosenza. Occhiuto passi dalle parole ai fatti: dopo la visita prescriva la cura"},"content":{"rendered":"<p>Dal titolo sembrava che il sindaco di Cosenza, Mario Occhiuto a seguito di malore si fosse recato, precauzionalmente, al Pronto Soccorso dell\u2019Ospedale Civile di Cosenza: quello dell\u2019Annunziata.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Infatti, il comunicato stampa di Palazzo dei Bruzi recita: \u201c<strong>Visita del sindaco Mario Occhiuto al pronto soccorso dell\u2019Ospedale dell\u2019Annunziata<\/strong>\u201d e, anche lui si fosse lamentato, non certo per le prestazioni dei medici ma, per la mancanza di strutture adeguate e di personale, perennemente sotto organico: \u201c<strong>Lavorate in condizioni assurde<\/strong>\u201d ma, proseguendo nella lettura mi sono reso conto, certo mia ignoranza, che per fortuna il sindaco Occhiuto si era recato al Pronto Soccorso dell\u2019Annunziata in \u201cvisita\u201d istituzionale e dopo aver visto la situazione in cui il personale sanitario opera, si \u00e8 lasciato andare ad un\u2019affermazione che certo condivido: <strong>\u201csiete degli eroi\u201d<\/strong>. A parte gli scherzi, anche se questo \u00e8 un argomento sul quale non c\u2019\u00e8 nulla da ironizzare, apprezziamo l\u2019interessamento di Occhiuto ed ancora pi\u00f9, la vasta utenza ospedaliera, apprezzerebbe una sua presa di posizione istituzionale: \u201c<strong>Essendo io la massima autorit\u00e0 sanitaria sul territorio, se voi medici lo ravviserete, oltre alla solidariet\u00e0 eserciter\u00f2 un atto concreto<\/strong>. Se cio\u00e8 dovesse venire a crearsi una eccessiva sproporzione fra i medici impiegati e i pazienti, il sindaco, con gli strumenti che la legge mette a disposizione, eserciter\u00e0 la prerogativa di massima autorit\u00e0 sanitaria del territorio con le decisioni del caso\u201d. Questo perch\u00e9, <strong>Sindaco, sulla sanit\u00e0<\/strong>, lo ha rilevato Lei stesso, <strong>non c\u2019\u00e8 pi\u00f9 tempo da perdere e, per non rendere la sua visita al nosocomio cosentino solo politico-istituzionale e di facciata, eserciti \u201cla prerogativa di massima autorit\u00e0 sanitaria del territorio con le decisioni del caso<\/strong>\u201d. Non c\u2019\u00e8 bisogno di dare i \u201cnumeri\u201d, purtroppo ai pi\u00f9 \u00e8 capitato di varcare la soglia del Pronto Soccorso all\u2019Annunziata di Cosenza e, nonostante l\u2019abnegazione dei medici e di tutto il personale, <strong>90mila pazienti all\u2019anno sembrano davvero sproporzionati rispetto alle \u201cturnazioni dei sanitari disponibili\u201d<\/strong>. Considerato che, come ha avuto modo anche di ribadire il presidente della Commissione sanit\u00e0 del Comune, Massimo Bozzo, \u201c<strong>al momento in tutto l\u2019ospedale mancano all\u2019incirca 30 medici\u201d. Qui, sindaco Occhiuto non si pu\u00f2 pi\u00f9 aspettare perch\u00e9 in gioco ci sono vite umane: eserciti \u201cun atto concreto<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal titolo sembrava che il sindaco di Cosenza, Mario Occhiuto a seguito di malore si fosse recato, precauzionalmente, al Pronto Soccorso dell\u2019Ospedale Civile di Cosenza: quello dell\u2019Annunziata.<\/p>\n","protected":false},"author":22,"featured_media":34089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-34088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34088"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34089"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}