{"id":34124,"date":"2014-06-20T07:37:52","date_gmt":"2014-06-20T05:37:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/festival-delle-utopie-realizzabili-a-tortora\/"},"modified":"2023-01-17T12:55:32","modified_gmt":"2023-01-17T11:55:32","slug":"14771-festival-delle-utopie-realizzabili-a-tortora","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14771-festival-delle-utopie-realizzabili-a-tortora\/","title":{"rendered":"Commercio equo-solidale: Festival delle Utopie Realizzabili a Tortora"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\">TORTORA (CS) &#8211; E&#8217; partito ufficialmente stamattina con una passeggiata sul mulo il festival della solidariet\u00e0 e sostenibilit\u00e0 ambientale.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il centro storico della cittadina tortorese ospiter\u00e0, oggi e domani, il Festival delle Utopie Realizzabili. L\u2019evento \u00e8 stato organizzato dall\u2019Associazione Cattivo Teatro con il patrocinio del Comune di Tortora. \u201cL\u2019amministrazione comunale \u2013 ha spiegato Sergio Tranchino, consigliere delegato alla Cultura \u2013 crede molto nelle tematiche riguardanti la sostenibilit\u00e0 ambientale e questa manifestazione offrir\u00e0 utili spunti di riflessione in tal senso. La nostra cittadina possiede territori di grande bellezza, che \u00e8 necessario preservare nel tempo\u201d. Il Festival delle Utopie Realizzabili si propone come macro contenitore all&#8217;interno del quale si svilupperanno incontri, dibattiti, workshop, eventi, dimostrazioni e laboratori incentrati sulle tematiche della sostenibilit\u00e0 ambientale. Nel corso delle due giornate si susseguiranno spettacoli, in particolare &#8220;Kairos&#8221; di e con Biagio Accardi, l&#8217;ideatore del &#8220;Viaggio Lento&#8221;, performance di body painting, mercatini con prodotti del territorio e la Bio-osteria dall&#8217;alba al tramonto. Gli spettacoli con cantastorie, proiezioni e dimostrazioni di pratiche che vanno dai massaggi shiatsu alle cure naturali inizieranno oggi a partire dalle 18.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORTORA (CS) &#8211; E&#8217; partito ufficialmente stamattina con una passeggiata sul mulo il festival della solidariet\u00e0 e sostenibilit\u00e0 ambientale.<\/p>\n","protected":false},"author":22,"featured_media":34125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-34124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34124"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34125"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}