{"id":34138,"date":"2014-06-20T10:49:19","date_gmt":"2014-06-20T08:49:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/rissa-per-amore-termina-a-colpi-di-crick-tre-arresti\/"},"modified":"2023-01-17T12:55:33","modified_gmt":"2023-01-17T11:55:33","slug":"14778-rissa-per-amore-termina-a-colpi-di-crick-tre-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14778-rissa-per-amore-termina-a-colpi-di-crick-tre-arresti\/","title":{"rendered":"Rissa per &#8216;amore&#8217; termina a colpi di crick, tre arresti"},"content":{"rendered":"<p>BISIGNANO (CS) &#8211; Litigio furibondo nei pressi del centro commerciale Il Castello a Bisignano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Intorno alle 18 di ieri tre giovani si sono azzuffati per una futile contesa amorosa. I carabinieri della locale stazione allertati dai presenti hanno sedato la rissa e provveduto ad arrestare i protagonisti della rissa culminata in un vero e proprio pestaggio a colpi di crick. Si tratta di tre disoccupati, tutti pregiudicati, volti non nuovi per le autorit\u00e0 bisignanesi. Il pi\u00f9 piccolo \u00e8 Matteo Martinez 21enne sposato e residente a Bisignano, ammanettto su corso Italia insieme ai fratelli Urso di Cerzeto: Antonello 27enne e il 22enne Luca. I tre, date le ferite provocate dal violento battibecco, sono stati soccorsi dal personale del 118 intervenuto sul posto. I sanitari hanno riscontrato per Martinez un trauma cranico con ferite sul cranio, distorsione del polso e accenno ernia per una prognosi di 20 giorni; lacerazione dell&#8217;arcata sopraccigliare ed ecchimosi giudicate guaribili in una settimana per Antonello Urso, mentre il fratello pi\u00f9 piccolo ha riportato diverse ecchimosi ed escoriazioni. Dopo essere stati curati dai medici dell&#8217;ospedale dell&#8217;Annunziata i tre giovani sono stati sottoposti agli arresti domiciliari in attesa di giudizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BISIGNANO (CS) &#8211; Litigio furibondo nei pressi del centro commerciale Il Castello a Bisignano.<\/p>\n","protected":false},"author":18,"featured_media":34139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-34138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34138"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34139"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}