{"id":34181,"date":"2014-06-23T06:22:00","date_gmt":"2014-06-23T04:22:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/oggi-gli-interrogatori-di-assessori-e-senatori-accompagnamento-coatto-in-aula\/"},"modified":"2023-01-17T12:55:39","modified_gmt":"2023-01-17T11:55:39","slug":"14801-oggi-gli-interrogatori-di-assessori-e-senatori-accompagnamento-coatto-in-aula","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14801-oggi-gli-interrogatori-di-assessori-e-senatori-accompagnamento-coatto-in-aula\/","title":{"rendered":"Oggi interrogatori di assessori e senatori, accompagnamento coatto in aula"},"content":{"rendered":"<p>CATANZARO &#8211; Tallini l&#8217;assessore regionale al Personale esponente di Forza Italia e Zoccali direttore generale della Presidenza risultano indagati per abuso d&#8217;ufficio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La vicenda riguarda due dirigenti regionali che sarebbero rimasti in servizio nonostante la scadenza del loro contratto. Sul banco degli imputati una delibera di giunta con la quale vennero stabilizzati i dirigenti Valeria Fedele e Giorgio Margiotta. La delibera fu poi ritirata grazie a una sentenza della Corte costituzionale che vieta l&#8217;assunzione di personale in assenza di un bando di concorso. Ma il Dipartimento del personale, quello afferente al forzista di Scopelliti, Domenico Tallini, avrebbe poi redatto una nuova bozza in sostituzione di quella illegittima che in Giunta per\u00f2 non \u00e8 mai arrivata. Secondo il magistrato Dominijanni, l&#8217;assessore non present\u00f2 la bozza di delibera che annullava la precedente abusando delle sue funzioni nella nomina dei due dirigenti.<strong> A rispondere sulle presunte assunzioni clientelari sar\u00e0 oggi un primo gruppo di assessori e l&#8217;attuale governatore della Regione Antonella Stasi convocati in quanto persone informate dei fatti<\/strong>. Gioved\u00ec invece sar\u00e0 la volta dei senatori Piero Aiello, Antonio Stefano Caridi, degli assessori Caligiuri, Mancini, Trematerra e degli ex assessori Fabrizio Capua e e Stillitani. Chi non si presenter\u00e0 di fronte al pm Dominijanni, per sottoporsi all&#8217;interrogatorio, sar\u00e0 prelevato accompagnato coattivamente alla presenza del magistrato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Tallini l&#8217;assessore regionale al Personale esponente di Forza Italia e Zoccali direttore generale della Presidenza risultano indagati per abuso d&#8217;ufficio.<\/p>\n","protected":false},"author":18,"featured_media":34182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34181"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34182"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}