{"id":34223,"date":"2014-06-24T09:01:28","date_gmt":"2014-06-24T07:01:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/bimbo-di-3-mesi-muore-per-un-malore-nella-caserma-dei-carabinieri\/"},"modified":"2023-01-17T12:55:41","modified_gmt":"2023-01-17T11:55:41","slug":"14822-bimbo-di-3-mesi-muore-per-un-malore-nella-caserma-dei-carabinieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14822-bimbo-di-3-mesi-muore-per-un-malore-nella-caserma-dei-carabinieri\/","title":{"rendered":"Bimbo muore per un malore nella caserma dei carabinieri"},"content":{"rendered":"<p>TAURIANOVA (RC) &#8211; La mamma \u00e8 una giovane di origine romena di 19 anni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il bimbo, di sei mesi, aveva accusato un malore mentre la madre lo stava allattando. E&#8217; successo a Taurianova dove la donna, dopo aver chiesto aiuto ad un automobilista di passaggio, \u00e8 stata accompagnata alla locale caserma della Compagnia dei carabinieri. Nonostante l&#8217;intervento del 118 allertato dai militari il bambino \u00e8 morto nella caserma. Ancora non si conoscono con certezza le cause del decesso. Secondo le prime ricostruzione al 19enne, era sola in casa, quando si \u00e8 accorta che il bambino presentava dei problemi e, in preda al panico, \u00e8 corsa fuori dall&#8217;abitazione per chiedere aiuto. Successivamente, anche per lo shock subito, non \u00e8 stata in grado di dare una spiegazione all&#8217;accaduto ma l&#8217;ipotesi pi\u00f9 verosimile \u00e8 che il bambino possa morto a causa di un rigurgito. Del decesso del piccolo \u00e8 stata informata l&#8217;autorit\u00e0 giudiziaria anche se, al momento, non \u00e8 stata disposta l&#8217;effettuazione dell&#8217;esame autoptico. A rendere nota la vicenda intervengono \u00e8 stato l&#8217;Osservatorio sui diritti dei minori, con un comunicato a firma del presidente, Antonio Marziale, e del vicepresidente Antonino Napoli. &#8220;Desta sconcerto &#8211; dicono &#8211; il fatto che una madre, in piena emergenza, debba ricorrere all&#8217;aiuto dei militari dell&#8217; Arma per prestare soccorso al suo bambino. Non diciamo che il piccolo si sarebbe potuto salvare, perch\u00e9 non conosciamo i risvolti intrinseci della vicenda, ma certo \u00e8 che \u00e8 inaccettabile lasciare un&#8217;utenza di oltre quindicimila abitanti sprovvista di un ospedale per le prime emergenze&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TAURIANOVA (RC) &#8211; La mamma \u00e8 una giovane di origine romena di 19 anni.<\/p>\n","protected":false},"author":22,"featured_media":34224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34223"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34224"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}