{"id":34384,"date":"2014-06-30T09:24:37","date_gmt":"2014-06-30T07:24:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/stasera-rocco-hunt-in-calabria-per-cantare-a-verita\/"},"modified":"2023-01-17T12:55:51","modified_gmt":"2023-01-17T11:55:51","slug":"14906-stasera-rocco-hunt-in-calabria-per-cantare-a-verita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14906-stasera-rocco-hunt-in-calabria-per-cantare-a-verita\/","title":{"rendered":"Rocco Hunt con &#8216;A&#8217; verit\u00e0&#8217; apre stasera i concerti estivi calabresi"},"content":{"rendered":"<p>MAIDA (CZ) &#8211; Il giovane cantante partenopeo si esibir\u00e0 al Centro due Mari a partire dalle 21.30.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dopo la vittoria al Festival di Sanremo tra le nuove proposte, il Premio Luzzati, il Premio Assomusica, Mtv e Music Award, domani sera al Centro Due Mari di Maida, tra Lamezia Terme e Catanzaro, \u00e8 in arrivo per il giovane rapper salernitano Rocco Hunt un ennesimo riconoscimento che conferma il suo 2014 straordinario: il \u201cRiccio d\u2019Argento\u201d del celebre orafo crotonese Gerardo Sacco, premio di \u201cFatti di Musica Radio Juke Box Estate 2014\u201d, la ventottesima edizione della rassegna del Miglior Live d\u2019Autore diretta da Ruggero Pegna che si svolge, come ogni anno, in Calabria. Il riconoscimento gli \u00e8 stato assegnato come \u201crivelazione dell\u2019anno\u201d per il brano vincitore del festival, \u201cNu juorno buono\u201d, diventato uno dei successi pi\u00f9 amati in particolare dai giovanissimi e \u201c\u2019A Verit\u00e0\u201d, l\u2019 album pubblicato dopo il festival, subito in cima alle classifiche, che visto la collaborazione di stelle come Federico Zampaglione, Eros Ramazzotti ed Enzo Avitabile, oltre a quelle dei rapper Clementino, Noyz Narcos ed Ensi. Il concerto a Maida inizier\u00e0 alle ore 21.30. I biglietti sono disponibili nelle prevendite abituali e Ticketone e, a partire dalle ore 18.30, anche presso la biglietteria all\u2019ingresso&nbsp; della grande Area Concerti Due Mari. Dopo il via con Rocco Hunt, \u201cFatti di Musica Estate\u201d proseguir\u00e0 il 3 e 4 agosto in Piazza Umberto 1\u00b0 a Zungri, vicino Tropea, rispettivamente con Micaela e Loredana Bert\u00e8 (ingresso libero), il 5 agosto nell\u2019Anfiteatro di Palmi con l\u2019unica tappa degli Afterhours, il 6 agosto con l\u2019unico live in Calabria del \u201cMuseica Tour\u201d di Caparezza all\u2019Arena Magna Graecia di Catanzaro Lido, l\u20198 e 9 agosto in piazza Umberto 1\u00b0 a Girifalco con Giuliano Gabriele e il Parto delle Nuvole Pesanti (ingresso libero), il 15 agosto nel Teatro dei Ruderi di Cirella a Diamante con l\u2019attesissimo live di Pino Daniele. \u201cFatti di Musica Radio Juke Box Estate 2014\u201d \u00e8 realizzata col partenariato della Camera di Commercio di Catanzaro e dell\u2019Assessorato alla Cultura della Regione Calabria; inoltre, con il Patrocinio dei Comuni ospitanti e la collaborazione di Helldorado Live, \u201cLa Notte dei Briganti contro tutte le mafie\u201d di Girifalco, Comitato Madonna della Neve di Zungri, Associazione Teatro dei Ruderi di Cirella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MAIDA (CZ) &#8211; Il giovane cantante partenopeo si esibir\u00e0 al Centro due Mari a partire dalle 21.30.<\/p>\n","protected":false},"author":22,"featured_media":34385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34384"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34385"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}