{"id":34411,"date":"2014-07-01T09:13:59","date_gmt":"2014-07-01T07:13:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/camion-a-celico-si-scaricano-i-rifiuti-nella-presila-ma-non-era-illegale\/"},"modified":"2023-01-17T12:55:53","modified_gmt":"2023-01-17T11:55:53","slug":"14920-camion-a-celico-si-scaricano-i-rifiuti-nella-presila-ma-non-era-illegale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14920-camion-a-celico-si-scaricano-i-rifiuti-nella-presila-ma-non-era-illegale\/","title":{"rendered":"Camion a Celico: si scaricano i rifiuti nella Presila, ma non era illegale?"},"content":{"rendered":"<p><span class=\"fbPhotosPhotoCaption\"><span class=\"hasCaption\">COSENZA &#8211; &#8216;Che interesse ha Ecologia Oggi, cui titolare \u00e8 Guarascio che gestisce l&#8217;inceneritore di Gioia Tauro, a far funzionare la differenziata a Cosenza? Nessuno&#8217;.<\/span><\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span class=\"fbPhotosPhotoCaption\"><span class=\"hasCaption\">La riflessione di un ingegnere ambientale, attivista del Comitato Ambientale Presilano, all&#8217;alba di una nuova emergenza rifiuti fa luce sulla necessit\u00e0 di ampliare le discariche e costruire un termovalorizzatore nel cosentino. Eppure i dati divulgati dall&#8217;ISPRA sull&#8217;andamento della differenziata nella provincia bruzia sono pi\u00f9 che positivi. Ma non importa. L<strong>a Regione vuole megadiscariche ed inceneritori: Battaglina, Scala Coeli, Bisignano, Gioia Tauro e Celico.<\/strong> Ed \u00e8 proprio nella discarica di Celico che, ad oggi, pare non accetti pi\u00f9 rifiuti dai Comuni della Presila perch\u00e8, a detta degli uffici tecnici, la Regione non ha ancora pagato gli sversamenti avvenuti da fine Marzo in poi, si registra un anomalo andirivieni di camion che sversano e vanno via. <br \/><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"fbPhotosPhotoCaption\">&nbsp;<\/span>Il sito di contrada San Nicola, anche se a regime ridotto, continua ad essere operativo. L&#8217;ingegnere attivista racconta che &#8220;ieri mattina sono passati dei camion che sembravano quelli di Calabra Maceri. Noi non abbiamo la possibilit\u00e0 di fermarli e controllare la bolla per vedere cosa trasportano lo dovebbe fare la forestale, il Noe o la provinciale. Abbiamo visto che hanno conferito e che continuano a lavorare anche di notte. Presumiamo che si tratti di rifiuti provenienti da aziende di privati.<strong> Dall&#8217;odore sembrano rifiuti indifferenziati, ben che vada sar\u00e0 organico. E&#8217; assurdo. Il trattamento dell&#8217;umido a Celico ora non pu\u00f2 avvenire perch\u00e8 le vasche adibite al trattamento e alla produzione del compost sono occupate dai rifiuti indifferenziati<\/strong> e il capannone in cui dovevano trattare l&#8217;organico non \u00e8 pronto. La Calabra Maceri che doveva dotarsi di un impianto entro il 30 Maggio non lo ha fatto.<\/p>\n<p>&nbsp;<\/p>\n<p>Viene il sospetto che si voglia emulare il modello Campania <strong>creando l&#8217;emergenza per poi autorizzare la costruzione di nuovi inceneritori e discariche. Potrebbe poi succedere come ad Acerra che non ci sono abbastanza rifiuti da bruciare. Il termovalorizza diventa cos\u00ec un business per i gestori che accolgono i rifiuti da altre Regioni, ovviamente a pagamento.<\/strong> Infatti hanno subito accettato di smaltire i nostri rifiuti. A breve si ripresenter\u00e0 la situazione di quest&#8217;inverno con l&#8217;aggravante che il caldo creer\u00e0 seri problemi igienico-sanitari in citt\u00e0. Gi\u00e0 su via Popilia e Bosco de Nicola la puzza \u00e8 ovunque. Noi non staremo con le mani in mano ad aspettare che riversino l&#8217;indifferenziato a Celico ignorando ogni normativa vigente.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli ampliamenti vietati dalla forestale sono stati fatti comunque, la legge Galasso vieta che una discarica sia ubicata a pi\u00f9 di 800 metri di altitudine non \u00e8 rispettata, cos\u00ec come non lo sono le distanze da centri abitati, provinciali e torrenti, in quest&#8217;ultimi inoltre dalla vecchia discarica (mai bonificata) viene rivesato il percolato, mentre <strong>i livelli di manganese ormai sono altissimi e come successo a Pianette di Cotronei potrebbero essere collegati alla presenza della discarica<\/strong>&#8220;. Le norme di legge tutelano la salute degli abitanti della Presila. A farle rispettare per\u00f2 dovranno pensarci i cittadini e gli ambientalisti che hanno gi\u00e0 ricostruito la casetta per un presidio permanente in difesa del territorio. Si anticipa un&#8217;estate &#8216;calda&#8217; in contrada San Nicola.<span id=\"fbPhotoSnowliftCaption\" class=\"fbPhotosPhotoCaption\"><span class=\"hasCaption\"><br \/> <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8216;Che interesse ha Ecologia Oggi, cui titolare \u00e8 Guarascio che gestisce l&#8217;inceneritore di Gioia Tauro, a far funzionare la differenziata a Cosenza? Nessuno&#8217;.<\/p>\n","protected":false},"author":18,"featured_media":34412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-34411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34411"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34412"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}