{"id":34468,"date":"2014-07-04T04:47:02","date_gmt":"2014-07-04T02:47:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/incidente-mortale-nel-cosentino-la-vittima-e-un-dentista-61enne\/"},"modified":"2023-01-17T12:55:56","modified_gmt":"2023-01-17T11:55:56","slug":"14950-incidente-mortale-nel-cosentino-la-vittima-e-un-dentista-61enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14950-incidente-mortale-nel-cosentino-la-vittima-e-un-dentista-61enne\/","title":{"rendered":"Incidente mortale nel Cosentino, la vittima \u00e8 un dentista 61enne"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; La vittima viaggiava a bordo della sua Audi che si \u00e8 scontrata contro un altro veicolo guidata da un 58enne di Frascineto (Cs).<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un dentista di 61 anni, Giovanni Martire, ha perso la vita a seguito di un incidente stradale verificatosi sulla strada provinciale che collega Castrovillari con Civita. Secondo le prime ricostruzioni le due auto si sarebbero scontrate. Le due persone sarebbero riuscite a scendere dalle rispettive auto dopo lo scontro ma Martire, accasciatosi al suolo \u00e8 poi deceduto sull&#8217;asfalto. Sul posto sono intervenuti i vigili del fuoco, un&#8217;ambulanza del 118. Il 51enne rimasto ferito \u00e8 stato portato nell&#8217;ospedale di Castrovillari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; La vittima viaggiava a bordo della sua Audi che si \u00e8 scontrata contro un altro veicolo guidata da un 58enne di Frascineto (Cs).<\/p>\n","protected":false},"author":19,"featured_media":34469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-34468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34468"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34469"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}