{"id":34495,"date":"2014-07-04T13:13:08","date_gmt":"2014-07-04T11:13:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/nessun-partito-alle-primarie-netto-risparmio-per-le-casse-della-regione\/"},"modified":"2023-01-17T12:55:58","modified_gmt":"2023-01-17T11:55:58","slug":"14964-nessun-partito-alle-primarie-netto-risparmio-per-le-casse-della-regione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/14964-nessun-partito-alle-primarie-netto-risparmio-per-le-casse-della-regione\/","title":{"rendered":"Nessun partito alle primarie, netto risparmio per le casse della Regione"},"content":{"rendered":"<p>CATANZARO &#8211; Scongiurato il rischio di impoverire ulteriormente le finanze della Regione Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il Dipartimento della Presidenza della Giunta regionale &#8211; informa una nota dell&#8217;Ufficio stampa &#8211; ha dato notizia che alle dodici di oggi sono scaduti i termini, come previsto, per la presentazione di candidature, da parte di partiti e gruppi politici, alle elezioni primarie per la carica di Presidente della Regione della Calabria.<strong> L&#8217;Ufficio elettorale regionale, coordinato dal dirigente Luigi Bulotta, all&#8217;ora stabilita, non ha registrato alcuna richiesta.<\/strong> La Presidente facente funzione della Regione Antonella Stasi ha commentato positivamente la notizia &#8220;in quanto &#8211; ha detto &#8211; noi abbiamo dato seguito a quanto previsto dalla legge in materia. Ma il fatto che non vi sia stata nessuna richiesta ci consente di avere un forte risparmio in termini di spesa che l&#8217;operazione elettorale, qualora fosse stata attivata, ci avrebbe costretto ad affrontare, pur nella esiguit\u00e0 delle nostre finanze&#8221;. I partiti e le coalizioni che vorranno scegliere il candidato presidente attraverso l&#8217;uso delle primarie lo potranno comunque fare a loro spese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Scongiurato il rischio di impoverire ulteriormente le finanze della Regione Calabria.<\/p>\n","protected":false},"author":22,"featured_media":34496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34495"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34496"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}