{"id":34662,"date":"2014-07-13T04:19:25","date_gmt":"2014-07-13T02:19:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/museo-del-fumetto-giovedi-a-cosenza-l-inaugurazione\/"},"modified":"2023-01-17T12:56:11","modified_gmt":"2023-01-17T11:56:11","slug":"15051-museo-del-fumetto-giovedi-a-cosenza-l-inaugurazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15051-museo-del-fumetto-giovedi-a-cosenza-l-inaugurazione\/","title":{"rendered":"&#8216;Museo del Fumetto&#8217;, gioved\u00ec a Cosenza l&#8217;inaugurazione"},"content":{"rendered":"<p>COSENZA &#8211; Unico nel suo genere nel Mezzogiorno d&#8217;Italia, il Museo del Fumetto \u00e8 importante tappa dell&#8217;articolato percorso culturale, lungo otto anni, intrapreso con il Festival Le Strade del Paesaggio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Gioved\u00ec prossimo 17 luglio, alle 18.30, negli spazi della Galleria d&#8217;Arte Provinciale Santa Chiara, nel centro storico di Cosenza, si terr\u00e0 la cerimonia di inaugurazione del Museo del Fumetto, che conserva tantissime opere nate dalla fantasia degli autori che hanno conosciuto la citt\u00e0 di Cosenza, le sue verit\u00e0 e le sue leggende. Il patrimonio di opere esposte vanta le firme pi\u00f9 prestigiose del fumetto italiano. Si parte da <strong>Tanino Liberatore<\/strong>, creatore di opere come <strong>Ranxerox<\/strong> che hanno fatto la storia del fumetto d&#8217;autore, sino ad <strong>Angelo Stano, Gianluca Cestaro e Bruno Brindisi,<\/strong> le cui matite hanno dato e continuano a dare forma e sostanza a personaggi cult quali Tex e Dylan Dog, passando per il virtuoso tratto di Marina Comandini Pazienza. E ancora il papa&#8217; di Ken Parker,<strong> Ivo Milazzo<\/strong>, autore di un bellissimo ritratto di Fabrizio De Andre&#8217;, cantautore che ispiro&#8217; un&#8217;intera edizione del Festival con importanti opere che saranno in mostra nel Museo al gran completo.<\/p>\n<p>&nbsp;<\/p>\n<p>Accanto agli autori &#8220;tradizionali&#8221; dell&#8217;arte sequenziale, grandi artisti del pop surrealismo internazionale tra i quali Jim Avignon, Nicola Alessandrini e David Vecchiato che si sono cimentati, con originalita&#8217;, nel racconto del territorio, reinterpretando luoghi e racconti della citta&#8217; vecchia attraverso i linguaggi dell&#8217;estetica contemporanea. Molto piu&#8217; che semplici disegni, le opere nel Museo del Fumetto esprimono una sublime sintesi di processi culturali collettivi testimoniando la ricchezza semantica dei nostri territori ed evidenziando come dal legame tra tradizione ed innovazione possano originarsi percorsi virtuosi per il prossimo futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Unico nel suo genere nel Mezzogiorno d&#8217;Italia, il Museo del Fumetto \u00e8 importante tappa dell&#8217;articolato percorso culturale, lungo otto anni, intrapreso con il Festival Le Strade del Paesaggio.<\/p>\n","protected":false},"author":22,"featured_media":34663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-34662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34662"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34663"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}