{"id":34699,"date":"2014-07-14T10:47:25","date_gmt":"2014-07-14T08:47:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/blitz-della-guardia-costiera-nei-depuratori-del-tirreno\/"},"modified":"2023-01-17T12:56:13","modified_gmt":"2023-01-17T11:56:13","slug":"15069-blitz-della-guardia-costiera-nei-depuratori-del-tirreno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15069-blitz-della-guardia-costiera-nei-depuratori-del-tirreno\/","title":{"rendered":"Blitz dei militari nei depuratori del Tirreno, sequestrati sei impianti"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; La Guardia Costiera di Vibo Valentia ha oggi posto i sigilli a sei impianti comunali di depurazione nel Golfo di Sant&#8217;Eufemia.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I gestori delle strutture che si occupano dei reflui dei bacini del fiume Amato e del fiume Savuto avranno trenta giorni di tempo per provvedere a porre rimedio alle criticit\u00e0 rilevate dalla Procura della Repubblica di Lamezia Terme. Intanto diciotto hanno provveduto nella mattinata a notificare i provvedimenti di sequestro agli indagati, ai custodi e ad un dipendente dell\u2019ATO 1 di Cosenza, nominato in qualit\u00e0 di esperto, che dovr\u00e0 collaborare alla verifica dell\u2019eliminazione delle anomalie riscontrate presso gli impianti.<\/p>\n<p>&nbsp;<\/p>\n<p>I depuratori ai quali sono stati apposti i sigilli sono: <br \/>&#8211; L\u2019impianto di depurazione consortile sito in <strong>localit\u00e0 Marina del Comune di&nbsp; Nocera Terinese<\/strong>, per deposito incontrollato di fanghi non smaltiti secondo la tempistica prevista per legge. Infatti il mantenimento dei fanghi di depurazione nelle vasche dell\u2019impianto, provoca ad oggi, oltre al malfunzionamento del sistema depurativo, anche un trascinamento degli stessi nello scarico finale, che sfocia in mare tramite il torrente grande affluente del Fiume Savuto. In particolare al momento dei controlli i Guardacoste hanno, a conferma di ci\u00f2, accertato e filmato il trascinamento di fanghi all\u2019uscita dell\u2019impianto. Deferito alle autorit\u00e0 giudiziarie il sindaco pro tempore del Comune di Nocera.&nbsp;<\/p>\n<p>&#8211; L\u2019impianto di depurazione sito in l<strong>ocalit\u00e0 Guarna del Comune di San Pietro a <\/strong><strong>Maida<\/strong>, ove \u00e8 stato accertato che i fanghi di depurazione non sono stati regolarmente smaltiti e si trovano depositati nei letti di essiccazione causando un non opportuno ciclo depurativo dei reflui fognari, con conseguente trascinamento allo scarico finale, confluente nel Fiume Amato. Deferiti due titolari delle imprese di gestione e conduzione degli impianti che si sono succedute nella gestione.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; I quattro impianti di depurazione del Comune di Serrastretta siti nelle <strong>localit\u00e0 Timpa Cancello, Trempa Migliuso, Fossa d\u2019Angoli, Costa Capoluogo<\/strong>, ove \u00e8 stato accertato che i fanghi di depurazione non sono stati regolarmente smaltiti e si trovano depositati nei letti di essiccazione causando un non opportuno ciclo depurativo dei reflui fognari, con conseguente trascinamento allo scarico finale, confluente nel Fiume Amato. In particolare tre dei quattro impianti ispezionati, sono risultati inattivi al momento del controllo. Deferiti il Sindaco pro tempore del Comune di Serrastretta e il Responsabile dell\u2019Area Tecnica.<\/p>\n<p>&nbsp;<\/p>\n<p>Dal mese di febbraio sono stati 85 gli impianti di depurazione comunali e privati sottoposti ai controlli della Guardia Costiera di Vibo sia sulla fascia costiera che nell\u2019entroterra su 36 comuni costieri e 4 provincie (Potenza &#8211; Cosenza &#8211; Catanzaro &#8211; Vibo). L\u2019operazione denominata \u201cMarechiaro 4\u201c, ha visto operare pi\u00f9 di 50 militari i quali hanno esperito ben 116 missioni percorrendo pi\u00f9 di 5.823 Km di vigilanza, ispezionando 66 Comuni, 309 stazioni di sollevamento, dalle cui verifiche sono scaturiti 36 verbali amministrativi per un ammontare di oltre 217.000 euro e nr.30 notizie di reato indirizzate alle Procure competenti per territorio (Lagonegro-Paola-Lamezia-Vibo). <br \/>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME &#8211; La Guardia Costiera di Vibo Valentia ha oggi posto i sigilli a sei impianti comunali di depurazione nel Golfo di Sant&#8217;Eufemia.<\/p>\n","protected":false},"author":22,"featured_media":34700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34699"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34700"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}