{"id":34765,"date":"2014-07-17T04:11:44","date_gmt":"2014-07-17T02:11:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/furti-alle-gioiellerie-e-a-personaggi-facoltosi-13-arresti\/"},"modified":"2023-01-17T12:56:17","modified_gmt":"2023-01-17T11:56:17","slug":"15102-furti-alle-gioiellerie-e-a-personaggi-facoltosi-13-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15102-furti-alle-gioiellerie-e-a-personaggi-facoltosi-13-arresti\/","title":{"rendered":"Furti alle gioiellerie e a personaggi facoltosi, 13 arresti"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Le indagini sono durate due anni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Stamattina \u00e8 scattata l&#8217;operazione dei carabinieri del Comando provinciale di Roma e di Reggio Calabria per l&#8217;esecuzione, di 13 ordinanze di custodia cautelare (di cui 9 in carcere e 4 agli arresti domiciliari) emesse dal gip di Reggio Calabria su richiesta della Procura. Gli arrestati sono ritenuti componenti di un gruppo specializzato in furti di ingente valore ai danni principalmente di gioiellerie e abitazioni private di facoltosi. Gioielli e preziosi i principali obbiettivi della &#8221;banda&#8221; che a Roma e Reggio Calabria ha messo a segno diversi colpi. I carabinieri hanno anche individuato basisti e ricettatori con il rinvenimento di refurtiva. L&#8217;accusa \u00e8 di associazione a delinquere finalizzata ai furti e alla ricettazione.<\/p>\n<p>&nbsp;<\/p>\n<p><strong> Tra gli obiettivi della banda, anche il Teatro Cilea <\/strong><\/p>\n<p>Il teatro di Reggio Calabria era nel mirino del gruppi di ladri sgominato questa mattina, ma il colpo and\u00f2 in fumo per l&#8217;intervento degli stessi militari che bloccarono tre uomini mentre si accingevano a forzare la cassaforte. I banditi tentarono il colpo la sera del 2 novembre 2011 perch\u00e9, secondo la ricostruzione fatta dai carabinieri, avevano informazioni che confermavano la presenza degli incassi delle ultime serate per una cifra ingente. La banda, secondo l&#8217;indagine coordinata dalla Procura della Repubblica di Reggio Calabria, per i colpi, l&#8217;organizzazione sfruttava le informazioni acquisite dai basisti operativi a Reggio Calabria, che erano insospettabili imprenditori specializzati nel posizionamento di impianti di condizionatori d&#8217;aria. Grazie a loro la banda riusciva ad ottenere informazione sulla refurtiva e le modalit\u00e0 di elusione degli impianti di allarme di abitazioni private e gioiellerie. Sfruttando poi le competenze nel campo dell&#8217;elettronica venivano manomessi ed inertizzati i sistemi di difesa passiva dei vari obbiettivi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Le indagini sono durate due anni.<\/p>\n","protected":false},"author":19,"featured_media":34766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34765"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34766"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}