{"id":34809,"date":"2014-07-18T04:10:01","date_gmt":"2014-07-18T02:10:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cosenza-calcio-arriva-in-prestito-il-difensore-esterno-zanini\/"},"modified":"2023-01-17T12:56:20","modified_gmt":"2023-01-17T11:56:20","slug":"15124-cosenza-calcio-arriva-in-prestito-il-difensore-esterno-zanini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15124-cosenza-calcio-arriva-in-prestito-il-difensore-esterno-zanini\/","title":{"rendered":"Cosenza Calcio, arriva in prestito il difensore esterno Zanini"},"content":{"rendered":"<p>COSENZA &#8211; Un nuovo arrivo nella rosa rossobl\u00f9.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La Societ\u00e0 Cosenza Calcio ha comunicato di aver tesserato il calciatore Matteo Zanini, proveniente dal Cesena, con la formula del prestito. Nato a Pavia, classe 1994, Zanini \u00e8 un difensore esterno, cresciuto nel settore giovanile del Milan ha compiuto tutta la trafila per poi passare al Pavia. Nella squadra della sua citt\u00e0 ha disputato 45 gare in due stagioni in Prima Divisione. Il rendimento elevato gli ha consentito di far parte della Nazionale Under 18 e Under 20 di Lega Pro. Il calciatore \u00e8 gi\u00e0 a disposizione del tecnico Cappellacci nel ritiro di Norcia dalla giornata di domenica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un nuovo arrivo nella rosa rossobl\u00f9.<\/p>\n","protected":false},"author":22,"featured_media":34810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-34809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34809"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34810"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}