{"id":34837,"date":"2014-07-18T20:00:00","date_gmt":"2014-07-18T18:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/calabria-novembre-al-voto\/"},"modified":"2023-01-17T12:56:22","modified_gmt":"2023-01-17T11:56:22","slug":"15140-calabria-novembre-al-voto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15140-calabria-novembre-al-voto\/","title":{"rendered":"Calabresi al voto a Novembre, le prime elezioni con il &#8216;Porcellissimum&#8217;"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Si andr\u00e0 alle urne il 9 o al massimo il 16 di Novembre. Con una legge elettorale confezionata dopo la condanna di Scopelliti e votata dalla sola maggioranza.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Soglia minima di sbarramento al 15%. E la legge finisce sui banchi della Corte Costituzionale. Il giudizio sulla legittimit\u00e0 della riforma potrebbe per\u00f2 ritardare le elezioni di mesi e mesi. Il che farebbe estremamante felice la compagine scopellitiana. I nuovi bandi europei 2014 &#8211; 2020 da gestire a partire, guarda caso, da Novembre fanno gola a tutti i parti\u00ecti in quanto estremamente funzionali alle campagne elettorali bipartisan.<strong> Appalti, consulenze, progetti. I fondi di Bruxelles potrebbero avere un ruolo di notevole importanza nella prossima tornata elettorale. A prescindere dalla data<\/strong>. Dopo gli annunci di Alfano sul voto in Calabria da far in contemporanea con Piemonte e Abruzzo a Novembre, ieri anche il presidente dell\u2019assemblea regionale Franco Talarico ha confermato la chiamata alle urne dei calabresi in autunno. Pesa per\u00f2 come una spada di Damocle l&#8217;attesa del giudizio della Corte Costituzionale a cui il ministro calabrese Maria Carmela Lanzetta \u00e8 stato costretto a ricorrere per obbligo di legge.<\/p>\n<p>&nbsp;<\/p>\n<p>Talarico invece continua ad affermare che difender\u00e0 le scelte prese con il nuovo statuto elettorale della Calabria. E sullo sbarramento il presidente dell\u2019assemblea regionale ha affermato che si tratta di una decisione volta ad &#8220;evitare la frantumazione delle rappresentanze&#8221; rassicurando che &#8220;dalla prossima conferenza dei presidenti dei gruppi consiliari di luned\u00ec prossimo, lavoreremo, anche alla luce della proposta del Pd di abbassare la soglia di sbarramento all&#8217;8%, per trovare una soluzione quanto pi\u00f9 possibile unitaria ed eventualmente modificare l&#8217;originaria soglia del 15%&#8221;. <strong>Intanto si ricorda che il &#8216;Porcellissimum&#8217;, la legge post-Scopelliti attraverso la quale i calabresi sceglieranno i propri rappresentanti, ha ridotto i collegi elettorali da cinque a tre individuati negli ex territori delle province di Catanzaro, Cosenza e Reggio Calabria.<\/strong> Ma su questo come sulla cancellazione del voto disgiunto Talarico \u00e8 certo che la Corte Costituzionale non ha posto alcuna censura. Insomma sarebbero solo cavilli risolvibili con un accordo tra i partiti che siedono in consiglio. Vedremo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Si andr\u00e0 alle urne il 9 o al massimo il 16 di Novembre. Con una legge elettorale confezionata dopo la condanna di Scopelliti e votata dalla sola maggioranza.<\/p>\n","protected":false},"author":18,"featured_media":34838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34837"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34838"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}