{"id":34885,"date":"2014-07-21T07:20:35","date_gmt":"2014-07-21T05:20:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/tredicenne-muore-mentre-gioca-a-calcetto-sul-lungomare\/"},"modified":"2023-01-17T12:56:25","modified_gmt":"2023-01-17T11:56:25","slug":"15165-tredicenne-muore-mentre-gioca-a-calcetto-sul-lungomare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15165-tredicenne-muore-mentre-gioca-a-calcetto-sul-lungomare\/","title":{"rendered":"Tredicenne muore mentre gioca a calcetto sul lungomare"},"content":{"rendered":"<div>CROTONE &#8211; Doveva essere una semplice partita tra amichetti nel campetto vicino al lido Kursaal, ma non \u00e8 stato cos\u00ec.<\/div>\n<p>  <!--more-->  <\/p>\n<div>Gianluca Ciaccio dopo aver sostenuto gli esami di terza media aveva raggiunto Crotone con la madre per trascorrere le proprie vacanze. Il padre li avrebbe raggiunti tra qualche giorno. Ma la villeggiatura per la famiglia Ciaccio non sar\u00e0 pi\u00f9 un lieto momento di relax. Il ragazzino di Civitavecchia, cui nonni vivono a Crotone, ieri sera intorno alle 22 stava giocando con i cuginetti e gli amici a pallone quando pare abbia avvertito un malore. Il tredicenne si \u00e8 cos\u00ec seduto per riposare, ma dopo pochi minuti si \u00e8 accasciato a terra esalando l&#8217;ultimo respiro sotto gli occhi increduli dei coetanei che stavano giocando con lui sino ad un attimo primo. Dai primi rilievi \u00e8 emerso che il decesso potrebbe essere riconducibile ad un attacco cardiaco. I sanitari accorsi sul posto hanno tentato ripetutamente di rianimare il piccolo, ma non c&#8217;\u00e8 stato nulla da fare. Gli operatori del 118 non hanno potuto far altro che constatare l&#8217;avvenuto decesso tra la calca di persone che incuriosite e preoccupate sono accorse nei pressi del campetto. Sconcerto e sgomento per i genitori di Gianluca cui vacanza si \u00e8 trasformata in un vero incubo dal quale sar\u00e0 difficile risvegliarsi.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Doveva essere una semplice partita tra amichetti nel campetto vicino al lido Kursaal, ma non \u00e8 stato cos\u00ec.<\/p>\n","protected":false},"author":18,"featured_media":34886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-34885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=34885"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/34885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/34886"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=34885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=34885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=34885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}