{"id":35066,"date":"2014-07-28T04:50:31","date_gmt":"2014-07-28T02:50:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/incidenti-stradali-scontro-motorino-auto-morto-sedicenne\/"},"modified":"2023-01-17T12:56:37","modified_gmt":"2023-01-17T11:56:37","slug":"15258-incidenti-stradali-scontro-motorino-auto-morto-sedicenne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15258-incidenti-stradali-scontro-motorino-auto-morto-sedicenne\/","title":{"rendered":"Incidenti stradali, sedicenne di Rossano muore all&#8217;ospedale di Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Si \u00e8 spento all&#8217;ospedale di Cosenza, il sedicenne rimasto coinvolto in un incidente a Rossano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Lo scontro contro un&#8217;auto, era accaduto nella notte tra gioved\u00ec e venerd\u00ec, mentre Francesco Morf\u00f2, di 16 anni, era a bordo del suo motorino. Il ragazzo era stato ricoverato in gravi condizioni prima nell&#8217;ospedale di Rossano ma a causa delle gravi condizioni, tra cui un trauma cranico, era stato poi trasferito nell&#8217;ospedale dell&#8217;Annunziata. I genitori hanno deciso di donare gli organi del sedicenne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si \u00e8 spento all&#8217;ospedale di Cosenza, il sedicenne rimasto coinvolto in un incidente a Rossano.<\/p>\n","protected":false},"author":19,"featured_media":35067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35066"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35067"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}