{"id":35174,"date":"2014-07-31T04:13:36","date_gmt":"2014-07-31T02:13:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/scossa-di-terremoto-di-magnitudo-3-5-tra-potenza-e-cosenza\/"},"modified":"2023-01-17T12:57:20","modified_gmt":"2023-01-17T11:57:20","slug":"15314-scossa-di-terremoto-di-magnitudo-3-5-tra-potenza-e-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15314-scossa-di-terremoto-di-magnitudo-3-5-tra-potenza-e-cosenza\/","title":{"rendered":"Scossa di terremoto di magnitudo 3.5 tra Potenza e Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; La terra ha tremato ancora nella zona del Pollino questa mattina alle 5.29.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una scossa di terremoto di magnitudo 3.5 \u00e8 stata registrata al confine tra Basilicata e Calabria, tra le province di Potenza e Cosenza. Secondo i rilevamenti dell&#8217;Istituto nazionale di geofisica e vulcanologia (Ingv), il sisma ha avuto ipocentro a 8,2 km di profondit\u00e0 ed epicentro in prossimit\u00e0 dei comuni potentini di Rotonda e Viggianello e di quello cosentino di Morano Calabro. Non si hanno al momento segnalazioni di danni a persone o cose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La terra ha tremato ancora nella zona del Pollino questa mattina alle 5.29.<\/p>\n","protected":false},"author":19,"featured_media":35175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-35174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35174"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35175"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}