{"id":3518,"date":"2012-09-12T06:02:09","date_gmt":"2012-09-12T04:02:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3518"},"modified":"2023-01-17T13:36:12","modified_gmt":"2023-01-17T12:36:12","slug":"591-catanzaro-nuovo-record-di-immersione-in-apnea-a-soverato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/591-catanzaro-nuovo-record-di-immersione-in-apnea-a-soverato\/","title":{"rendered":"Soverato: nuovo record di immersione in apnea. (Video)"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Homer Leuci<\/strong>, raggiungendo la profondit\u00e0 di 131 m, conquistato il record mondiale di apnea in assetto variabile regolamentato.<\/p>\n<p style=\"text-align: justify;\">Si \u00e8 svolto con successo nella &#8220;Baia di Soverato&#8221; oggi pomeriggio (11 settembre) alle ore 16:00 il primo tentativo di record del mondo di Homar Leuci, campione di fama mondiale d&#8217;apnea , che ha battuto il record mondiale nella disciplina \u201capnea profonda in assetto variabile\u201d regolamentato CMAS, raggiungendo i 131 metri di profondit\u00e0 .<\/p>\n<p style=\"text-align: justify;\">Homar Leuci ha effettuato la prova usando una zavorra di trenta chilogrammi e risalendo in superficie con le proprie forze dopo 2 minuti e 50&#8243;.<\/p>\n<p style=\"text-align: justify;\">All&#8217;emersione dell&#8217;atleta, dopo la conferma da parte dei medici e dei giudici della corretta esecuzione della prova, i presenti hanno accolto il record con gli applausi e il suono delle sirene delle imbarcazioni.<\/p>\n<p style=\"text-align: justify;\">All\u2019evento erano presenti anche due imbarcazioni dei Vigili del Fuoco, con a bordo i sommozzatori del Nucleo di Reggio Calabria, che hanno prestato assistenza ai subacquei del team di supporto, e Personale della Direzione Regionale VV.F. della Calabria.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">A bordo anche il Direttore Regionale Ing. Claudio De Angelis.<\/p>\n<p style=\"text-align: left;\" align=\"center\">&nbsp;<\/p>\n<p style=\"text-align: left;\" align=\"center\">Ministero dell\u2019Interno: DIREZIONE REGIONALE DEI VIGILI DEL FUOCO PER LA CALABRIA &#8211; UFFICIO RELAZIONI ESTERNE<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; <em>Il presidente della Provincia <strong>Wanda Ferro<\/strong> rivolge le proprie congratulazioni all\u2019atleta Homar Leuci, che ieri pomeriggio nello specchio di mare antistante Soverato ha stabilito il nuovo record mondiale di immersione in apnea profonda nella disciplina dell&#8217;assetto variabile regolamentato. La nuova distanza raggiunta dal campione di immersione \u00e8 di 131 metri in un tempo di 2 minuti e 50 secondi. \u201cIl nuovo record stabilito da Homar Leuci \u2013 dice Wanda Ferro \u2013 \u00e8 il giusto premio per il suo grande impegno, la sua dedizione, la passione per la sua disciplina sportiva e soprattutto l\u2019amore profondo che nutre per il mare, che affronta con grande rispetto, costruendo giorno dopogiorno, con continui ed intensi allenamenti, un rapporto di autentica simbiosi. E\u2019 per noi motivo di particolare orgoglio che l\u2019atleta milanese abbia scelto proprio la Baia di Soverato per tentare il nuovo record: una scelta dettata dalle caratteristiche uniche del nostro mare, ma anche dall\u2019amore per l\u2019ospitalit\u00e0 e il fascino della nostra terra. Complimenti a Homar Leuci e a tutta la squadra di professionisti e appassionati che lo ha affiancato in questa impresa, che alla fine ha avuto l\u2019epilogo che tutti ci aspettavamo: la riconquista del record mondiale. Un record che regala prestigio e lusso alla citt\u00e0 di Soverato e a tutta la nostra provincia, che ha sempre fatto il tifo per Homar Leuci e lo ha sostenuto nel raggiungimento di questo successo straordinario\u201d<\/em>.<\/p>\n<div class=\"k2_video\"><iframe loading=\"lazy\" title=\"Record immersione\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/pnbSDoA7Ea0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Homer Leuci, raggiungendo la profondit\u00e0 di 131 m, conquistato il record mondiale di apnea in assetto variabile regolamentato. Si \u00e8 svolto con successo nella &#8220;Baia di Soverato&#8221; oggi pomeriggio (11 settembre) alle ore 16:00 il primo tentativo di record del mondo di Homar Leuci, campione di fama mondiale d&#8217;apnea , che ha battuto il record [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-3518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3518"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/960"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}