{"id":35198,"date":"2014-07-31T12:29:56","date_gmt":"2014-07-31T10:29:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-comune-di-cosenza-raccoglie-medicinali-da-inviare-in-palestina\/"},"modified":"2023-01-17T12:57:23","modified_gmt":"2023-01-17T11:57:23","slug":"15327-il-comune-di-cosenza-raccoglie-medicinali-da-inviare-in-palestina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15327-il-comune-di-cosenza-raccoglie-medicinali-da-inviare-in-palestina\/","title":{"rendered":"Il Comune di Cosenza promuove raccolta medicinali da inviare in Palestina"},"content":{"rendered":"<p>COSENZA &#8211; Da Cosenza l\u2019appello a contribuire alla raccolta fondi per l\u2019invio di medicinali in Palestina.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L\u2019Assessore alla cooperazione internazionale Nicola Mayer\u00e0 interviene a sostegno della campagna lanciata congiuntamente dalle Ong italiane presenti in Palestina, finalizzata all\u2019invio di medicinali a Gaza. Per motivi logistici, pur essendo un appello di tutte le Ong operanti in Palestina, il conto di raccolta fondi \u00e8 quello di Terre des Hommes autorevole associazione internazionale che dal 1989 opera nelle aree di crisi. Chi desidera contribuire pu\u00f2 farlo utilizzando diverse modalit\u00e0:<\/p>\n<p>Via banca: Ag. 57 Milano del Monte dei Paschi di Siena. IBAN: IT53Z0103001650000001030344.<\/p>\n<p>Via posta: c\/c postale n. 321208<\/p>\n<p><span>Via web: <\/span><a>www.terredeshommes.it<\/a><span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; www. igiveonline.com\/campaigns\/medicine-per-gaza<\/span><\/p>\n<p><span>Causale: medicine Gaza<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Da Cosenza l\u2019appello a contribuire alla raccolta fondi per l\u2019invio di medicinali in Palestina.<\/p>\n","protected":false},"author":22,"featured_media":35199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-35198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35198"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35199"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}