{"id":35226,"date":"2014-08-01T11:43:56","date_gmt":"2014-08-01T09:43:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/sila-patrimonio-per-l-unesco-e-discarica-per-la-calabria\/"},"modified":"2023-01-17T12:57:24","modified_gmt":"2023-01-17T11:57:24","slug":"15341-sila-patrimonio-per-l-unesco-e-discarica-per-la-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15341-sila-patrimonio-per-l-unesco-e-discarica-per-la-calabria\/","title":{"rendered":"Sila: patrimonio per l\u2019Unesco e discarica per la Calabria"},"content":{"rendered":"<p>ROVITO (CS) &#8211; La presila cosentina accoglier\u00e0 i rifiuti indifferenziati provenienti da tutta la Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il Dipartimento Ambiente della Regione Calabria ha emesso un nuovo provvedimento che ribadisce la volont\u00e0 regionale di trasformare la discarica di Celico nel ricettacolo dei rifiuti indifferenziati dell\u2019intera Regione, in forza al perpetuo stato di emergenza e immobilismo in materia di rifiuti, in cui versa la Calabria da quasi un ventennio. I<strong>l nuovo dispositivo prevede lo sversamento aggiuntivo di 80 tonnellate giornaliere da parte della societ\u00e0 privata Ecologia Oggi Spa, provenienti dagli impianti pubblici di Crotone, Siderno e Rossano, dal 28 Luglio 2014, fino a data da destinarsi.<\/strong> Si tratta di residuo tal quale parzialmente trattato, caratterizzato da un odore acre e nauseabondo. Ancora una volta, una discarica nata per ricevere la frazione indifferenziata, viene usata impropriamente per accogliere rifiuti che non hanno subito particolari processi di differenziazione a monte e negli impianti preposti. E\u2019 necessario mettersi di traverso e fronteggiare l\u2019ennesima ingiustizia perpetrata ai danni di un territorio gi\u00e0 devastato e non valorizzato, per le sue immense potenzialit\u00e0, per colpa di chi vuole lucrare sul riciclo, recupero e smaltimento dei rifiuti, in barba ad ogni tentativo di virtuosismo e civilt\u00e0. E\u2019 giunta l\u2019ora di difendere la Nostra Terra, la Nostra salute, la Nostra vita. <strong>E\u2019 arrivato il momento di scendere in strada e lottare uniti per non rimanere sommersi dai rifiuti e dall\u2019inscindibile connubio tra ndrangheta e mala politica.<\/strong> Tale impianto da anni calpesta la dignit\u00e0 e la libert\u00e0 della popolazione coinvolta obbligandola anche nelle calde sere d&#8217;estate a rimanere chiusa in casa a causa della puzza nauseabonda e malsana che invade l&#8217;intera vallata sino alle porte di Cosenza. Per tutte queste motivazioni<strong> la popolazione di Rovito, Celico e di tutti i paesi interessati dalla presenza della discarica scenderanno in strada partecipando alla fiaccolata che partir\u00e0 domani, Sabato 2 Agosto, alle 21.30 dalla piazza di San Nicola a Motta di Rovito per giungere nella piazza principale del paese, piazza del Popolo.<\/strong>&nbsp;<\/p>\n<p style=\"text-align: right;\">Comitato Ambientale Presilano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROVITO (CS) &#8211; La presila cosentina accoglier\u00e0 i rifiuti indifferenziati provenienti da tutta la Calabria.<\/p>\n","protected":false},"author":21,"featured_media":35227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35226"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35227"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}