{"id":35238,"date":"2014-08-02T06:53:30","date_gmt":"2014-08-02T04:53:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ritrovati-i-16-scout-scomparsi-in-calabria-stanno-tutti-bene\/"},"modified":"2023-01-17T12:57:25","modified_gmt":"2023-01-17T11:57:25","slug":"15347-ritrovati-i-16-scout-scomparsi-in-calabria-stanno-tutti-bene","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15347-ritrovati-i-16-scout-scomparsi-in-calabria-stanno-tutti-bene\/","title":{"rendered":"Ritrovati i 16 scout scomparsi in Calabria, stanno tutti bene"},"content":{"rendered":"<p>SAN BENEDETTO ULLANO (CS) &#8211; E&#8217; stato scongiurato il peggio per i boy scout di cui ieri si erano perse le tracce.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sono stati ritrovati e stanno tutti bene i 16 scout di San Cesareo in provincia di Lecce che erano scomparsi nel pomeriggio a San Benedetto Ullano mentre stavano effettuando un&#8217;escursione. I ragazzi si erano smarriti e si erano fermati, dopo avere dato l&#8217;allarme con un telefono cellulare, in attesa dei soccorritori. A ritrovare i 16 scout sono stati gli uomini del Corpo forestale dello Stato, che insieme al Soccorso alpino ed ai vigili del fuoco avevano avviato le ricerche dei 16 scout dalla prima serata di ieri. Il ritrovamento \u00e8 avvenuto a &#8220;Laghicello&#8221; di San Benedetto Ullano, una localit\u00e0 ad oltre mille metri sul livello del mare. Gli scout hanno riferito ai soccorritori di avere smarrito la strada mentre facevano rientro al loro campo base. Nel momento del ritrovamento, nella zona faceva freddo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong> Il Commissario capo del Corpo forestale, Angelo Roseti,<\/strong> che ha coordinato l&#8217;intervento di soccorso ha spiegato che i 16 minori pugliesi avevano perso il contatto col gruppo di escursionisti, composto in tutto da una quarantina di scout, dopo averlo superato ed avevano poi smarrito la strada. &#8220;I ragazzi, per\u00f2 &#8211; ha aggiunto il funzionario della Forestale &#8211; hanno affrontato la situazione con molta sicurezza e senza mai farsi sopraffare dalla paura, mettendo in atto le conoscenze e le tecniche acquisite come scout. L&#8217;unico problema \u00e8 che nella zona, soprattutto col sopraggiungere dell&#8217;oscurit\u00e0, faceva freddo e c&#8217;era anche nebbia&#8221;. I contatti col gruppo di minori sono stati costanti grazie al cellulare di cui era in possesso una ragazza, che ha fornito ai soccorritori le indicazioni per consentire il ritrovamento del gruppo. I primi a trovare gli scout sono stati i vigili del fuoco dopo che l&#8217;area in cui erano scomparsi i ragazzi era stata individuata dal Corpo forestale. &#8220;Alla fine &#8211; ha detto Roseti &#8211; ha vinto il gioco di squadre ed ha avuto successo il &#8216;protocollo&#8217; d&#8217;intervento che \u00e8 stato attivato ed al quale hanno partecipato, insieme a noi ed ai vigili del fuoco, i carabinieri ed il Soccorso alpino&#8221;. <strong>Tutti<\/strong> i ragazzi comunque, a parte la paura, sono in <strong>buone condizioni<\/strong> fatta eccezione di <strong>una 12enne<\/strong>, che \u00e8 stata ricoverata <strong>in ospedale<\/strong> per una <strong>ferita alla testa<\/strong>. Le condizioni della ragazza, comunque, non destano alcuna preoccupazione. L&#8217;ipotesi che viene fatta dal Corpo forestale, che ha riferito la circostanza, \u00e8 che la ragazza si sia procurata la ferita battendo la testa contro un ramo o cadendo a terra dopo essere inciampata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN BENEDETTO ULLANO (CS) &#8211; E&#8217; stato scongiurato il peggio per i boy scout di cui ieri si erano perse le tracce.<\/p>\n","protected":false},"author":22,"featured_media":35239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35238"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35239"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}