{"id":35252,"date":"2014-08-03T04:30:25","date_gmt":"2014-08-03T02:30:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/l-estate-2014-a-saracena-ricca-di-appuntamenti\/"},"modified":"2023-01-17T12:57:26","modified_gmt":"2023-01-17T11:57:26","slug":"15354-l-estate-2014-a-saracena-ricca-di-appuntamenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15354-l-estate-2014-a-saracena-ricca-di-appuntamenti\/","title":{"rendered":"L&#8217;estate 2014 a Saracena ricca di appuntamenti"},"content":{"rendered":"<p>SARACENA (CS) \u2013 Punta sulla tradizionale arte del ricamo nella societ\u00e0 come patrimonio da rivalutare e sostenere.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La 40esima edizione della programmazione socio-culturale estiva di Saracena sar\u00e0 incentrata sulla valorizzazione del ricamo come arte, come possibilit\u00e0 di promozione turistica e culturale del Paese del Moscato Passito, presidio Slow Food. E si parte domani e marted\u00ec 5 agosto con il Wine Festival. Degustazioni, incontri, ristoranti all\u2019aperto, mostre, percorsi enogastronomici. Nell\u2019evento dedicato al vino, che si snoder\u00e0 dalla Villa a Piazza S. Lio, passando da Porta del Vaglio, nel centro storico, tra il Moscato ed i vini dei produttori locali, trova spazio anche la mostra del corredo del \u2018900 con la sfilata di biancheria intima d\u2019epoca. La mostra del corredo antico dotale, nuziale e di intimo, a cura della Pro Loco cittadina sar\u00e0 allestita in Via Carlo Pisacane e inaugurata alle ore 10 di marted\u00ec. Alle 21,30 dello stesso giorno sfileranno gli abiti d\u2019epoca e i capi di intimo di fine \u2018800-met\u00e0 \u2018900 e alle 22,30 lo spettacolo musicale dell\u2019associazione culturale Cattivo Teatro. Da mercoled\u00ec 6 agosto invece, spazio alla cultura con la presentazione del libro del prof. Vittorio Cappelli intitolata \u201cLa Belle Epoque italiana di Rio de Janeiro\u201d alle 19 in Piazza S.Lio. Gioved\u00ec 7 agosto, sar\u00e0 la volta, in Piazza Castello, dello spettacolo teatrale intitolato &#8220;A che servono questi quattrini&#8221; a cura dell\u2019associazione culturale Aprustrum. L\u2019appuntamento \u00e8 fissato alle ore 19. Stesso orario per la presentazione il giorno successivo, venerd\u00ec 8 agosto, del testo di Francesco Lo Giudice &#8220;Cambiare il Sud per cambiare l&#8217;Europa&#8221; in Piazza S.Lio. Il 9 e 10 agosto si rinnova l\u2019appuntamento con i festeggiamenti in onore del Santo patrono San Leone. L\u2019evento \u00e8 a cura del Comitato Festa. Gli appuntamenti a Saracena proseguiranno ancora con una storia di emigrazione raccontata da Giuseppe Galiardi nel suo \u201cDal Pollino a Milano con il cappotto del nonno\u201d la cui presentazione del libro si terr\u00e0 alle 18.30 sempre nella piazzetta san Lio il marted\u00ec successivo, 12 agosto. Il giorno di Ferragosto sar\u00e0 la volta della grande Festa della Montagna. La musica invece, sar\u00e0 il filo conduttore degli eventi previsti per il 17 agosto: la discoteca con serata musicale house a cura del DJ Matteo Diana; il 18 \u00e8 in programma lo spettacolo musicale &#8220;Il viaggio tra musica e tradizione navigando nel mare nostrum&#8221; a cura di Francesca Senatore e Saverio Pandolfi; il 19 agosto ancora, lo spettacolo musicale Briganti del Sellaro, ed il 22 con il concerto musicale a cura del Complesso Bandistico San Leone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SARACENA (CS) \u2013 Punta sulla tradizionale arte del ricamo nella societ\u00e0 come patrimonio da rivalutare e sostenere.<\/p>\n","protected":false},"author":22,"featured_media":35253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35252"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35253"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}