{"id":35354,"date":"2014-08-07T09:15:44","date_gmt":"2014-08-07T07:15:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cervelli-che-non-fuggono-la-migliore-ricerche-sul-3d-e-made-in-unical\/"},"modified":"2023-01-17T12:57:33","modified_gmt":"2023-01-17T11:57:33","slug":"15408-cervelli-che-non-fuggono-la-migliore-ricerche-sul-3d-e-made-in-unical","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15408-cervelli-che-non-fuggono-la-migliore-ricerche-sul-3d-e-made-in-unical\/","title":{"rendered":"Cervelli che non fuggono, la migliore ricerca sul 3D \u00e8 &#8216;made in Unical&#8217;"},"content":{"rendered":"<p>RENDE (CS) &#8211; Giuseppe Filippone lavora come ricercatore presso il Dipartimento di Matematica e Informatica dell&#8217;Universit\u00e0 della Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La miglior tesi italiana di dottorato di ricerca su 3D, virtualit\u00e0 e simulazione \u00e8 stata scritta da lui grazie agli studi condotti nei laboratori dell&#8217;Unical. Il premio per la migliore tesi di dottorato di ricerca su argomenti concernenti Modellazione, Simulazione e Realt\u00e0 Virtuale e le loro applicazioni, gli \u00e8 stato assegnato dal Movimento Italiano Modellazione e Simulazione (MIMOS) per la sua ricerca intitolata &#8220;Parallel and evolutionary applications to cellular automata models for mitigation of lava flow invasions&#8221;. Il dott. Filippone ha realizzato il suo importante lavoro sotto la supervisione dei professori Donato D\u2019Ambrosio e William Spataro, del Dipartimento di Matematica e Informatica dell&#8217;Unical, e del prof. Davide Marocco, della Plymouth University (UK), dove ha svolto uno stage di diversi mesi.<\/p>\n<p>&nbsp;<\/p>\n<p>Il prestigioso riconoscimento, accompagnato da un premio di 1.500 Euro, sar\u00e0 ufficialmente conferito al dott. Filippone a Roma, il prossimo 12 novembre, nell&#8217;aula Marconi del Consiglio Nazionale delle Ricerche, alla presenza di illustri esponenti dell&#8217;industria, dell&#8217;universit\u00e0 e della ricerca. Nell\u2019occasione, Filippone presentera` gli aspetti piu` innovativi e le potenzialita` di applicazione industriale dei risultati conseguiti nell&#8217;ambito del proprio Dottorato in Matematica e Informatica all&#8217;Universita` della Calabria. Il premio assegnato al Dott. Filippone costituisce un\u2019ulteriore conferma dell&#8217;altissima quali\u00e0, formativa e scientifica, del Dottorato di Ricerca in Matematica e Informatica dell&#8217;Universita` della Calabria, coordinato dal prof. Nicola Leone, Direttore del Dipartimento di Matematica e Informatica. <strong>Il risultato di Filippone, infatti, segue analoghi premi all&#8217;eccellenza delle ricerche di questo dottorato, tra cui, da ultimi, il premio per la miglior tesi di dottorato di Italia in Logica Computazionale conferito alla dott.ssa Annamaria Bria nel 2013 a Catania, e il prestigioso Premio ECCAI (European Coordinating Committee for Artificial Intelligence) per le migliori tesi di dottorato di Europa sull&#8217;Intelligenza Artificiale, assegnato a Mario Alviano a Toulouse in Francia nel 2012.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 significativo, infine, che meno di un mese fa` due membri del collegio dello stesso dottorato sono stati insigniti di importanti riconoscimenti internazionali: il prof. Gianluigi Greco ha ricevuto il &#8220;Kurt Goedel Research Prize&#8221; il 17 Luglio a Vienna, mentre il prof. Giuseppe Marino e` stato classificato tra &#8220;The world&#8217;s most influential scientific minds 2014&#8221;, a conferma che il Dottorato di Ricerca in Matematica e Informatica dell&#8217;Unical si fonda su un collegio dei docenti scientificamente eccellente, che forma dottori di alta qualificazione accademica e professionale. Il dott. Giuseppe Filippone, oggi, \u00e8 un brillante assegnista di ricerca presso il Dipartimento di Matematica e Informatica dell&#8217;Universit\u00e0 della Calabria, dove si \u00e8 gi\u00e0 distinto per capacit\u00e0 e impegno<i>.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; Giuseppe Filippone lavora come ricercatore presso il Dipartimento di Matematica e Informatica dell&#8217;Universit\u00e0 della Calabria.<\/p>\n","protected":false},"author":22,"featured_media":35355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,7],"tags":[],"class_list":["post-35354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35354"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35355"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}