{"id":35480,"date":"2014-08-13T11:01:45","date_gmt":"2014-08-13T09:01:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/rissa-tra-coniugi-e-vicino-di-casa-tre-arresti-e-due-feriti\/"},"modified":"2023-01-17T12:57:41","modified_gmt":"2023-01-17T11:57:41","slug":"15479-rissa-tra-coniugi-e-vicino-di-casa-tre-arresti-e-due-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15479-rissa-tra-coniugi-e-vicino-di-casa-tre-arresti-e-due-feriti\/","title":{"rendered":"Rissa tra coniugi e vicino di casa, tre arresti e due feriti"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211;&nbsp;All&#8217;origine del litigio presunte molestie subite dalla donna.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tre persone, marito e moglie ed un loro vicino di casa, sono stati arrestati e posti ai domiciliari dagli agenti delle volanti della Questura di Reggio Calabria, per rissa aggravata. Secondo la ricostruzione della polizia, all&#8217;origine della rissa vi sarebbero state presunte molestie messe in atto dal vicino nei confronti della donna. I coniugi hanno quindi affrontato l&#8217;uomo armati di bastoni, mentre l&#8217;altro si \u00e8 difeso con due coltelli. I due uomini sono rimasti feriti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211;&nbsp;All&#8217;origine del litigio presunte molestie subite dalla donna.<\/p>\n","protected":false},"author":22,"featured_media":35481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35480"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35481"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}